{"id":80337,"date":"2016-04-04T11:19:50","date_gmt":"2016-04-04T09:19:50","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=80337"},"modified":"2016-04-04T11:19:50","modified_gmt":"2016-04-04T09:19:50","slug":"taranto-uno-scippo-da-trentamila-euro","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2016\/04\/04\/taranto-uno-scippo-da-trentamila-euro\/","title":{"rendered":"TARANTO, UNO SCIPPO DA TRENTAMILA EURO"},"content":{"rendered":"<p><img decoding=\"async\" loading=\"lazy\" width=\"264\" height=\"191\" title=\"untitled\" class=\"aligncenter size-full wp-image-80338\" alt=\"\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2016\/04\/untitled.png\" \/>(g.m.)______Scippo &#8220;ricco&#8221; questa mattina per i\u00a0due malviventi che questa mattina a Taranto, su viale Magna Grecia (nella foto), all&#8217; altezza di via Dalmazia, hanno portato via la borsa in cui un imprenditore aveva messo i soldi che stava per andare a versare in banca.<\/p>\n<p>Il bottino \u00e8 di trenta mila\u00a0euro.<\/p>\n<p>Dopo averlo evidentemente seguito, informati delle sue abitudini, aspettando solamente il momento giusto, questa mattina\u00a0verso le 9 gli scippatori sono entrati in azione, impossessandosi con violenza della borsa e facendo cadere a terra l&#8217; uomo, per poi dileguarsi senza lasciare traccia.<\/p>\n<p>Sul posto, i Carabinieri, che hanno avviato le indagini.<\/p>\n<p>&nbsp;<\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2016\/04\/04\/taranto-uno-scippo-da-trentamila-euro\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2016\/04\/04\/taranto-uno-scippo-da-trentamila-euro\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>(g.m.)______Scippo &#8220;ricco&#8221; questa mattina per i\u00a0due malviventi che questa mattina a Taranto, su viale Magna Grecia (nella foto), all&#8217; altezza di via Dalmazia, hanno portato via la borsa in cui un imprenditore aveva messo i soldi che stava per andare a versare in banca. Il bottino \u00e8 di trenta mila\u00a0euro. Dopo averlo evidentemente seguito, informati [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":80338,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[69],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/80337"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=80337"}],"version-history":[{"count":2,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/80337\/revisions"}],"predecessor-version":[{"id":80340,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/80337\/revisions\/80340"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/80338"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=80337"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=80337"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=80337"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}