{"id":8038,"date":"2012-12-06T12:42:15","date_gmt":"2012-12-06T12:42:15","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=8038"},"modified":"2012-12-06T12:42:15","modified_gmt":"2012-12-06T12:42:15","slug":"progetto-agroquality","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2012\/12\/06\/progetto-agroquality\/","title":{"rendered":"PROGETTO AGROQUALITY"},"content":{"rendered":"<p><strong><em><a href=\"https:\/\/www.leccecronaca.it\/index.php\/2012\/12\/06\/progetto-agroquality\/written-stop-smoking\/\" rel=\"attachment wp-att-8039\"><img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2012\/12\/cuoca-150x150.jpg\" alt=\"\" width=\"150\" height=\"150\" class=\"alignleft size-thumbnail wp-image-8039\" \/><\/a><a href=\"https:\/\/www.leccecronaca.it\/index.php\/2012\/12\/06\/progetto-agroquality\/olio-oliva-siviglia\/\" rel=\"attachment wp-att-8040\"><img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2012\/12\/olio-oliva-siviglia-150x150.jpg\" alt=\"\" width=\"150\" height=\"150\" class=\"alignleft size-thumbnail wp-image-8040\" \/><\/a>Un workshop tecnico di partenariato si terr\u00e0 \u00a0a Lecce per parlare del progetto che punta a migliorare le prestazioni\u00a0 delle piccole e medie imprese che producono olivo d\u2019oliva. <\/em><\/strong><\/p>\n<p><strong><em>L\u2019appuntamento \u00e8 fissato per gioved\u00ec 6 dicembre, alle ore 10, ai Teatini<br \/>\n<\/em><\/strong>Continua l\u2019attivit\u00e0 del Comune di Lecce nell\u2019ambito della costruzione e dello sviluppo di un modello per la qualit\u00e0 di coltivazione delle olive e la certificazione dei processi di olivicoltura.<br \/>\n<strong>Gioved\u00ec 6 dicembre, alle ore 10, all\u2019ex Convento dei Teatini <\/strong>del Comune di<strong> <\/strong>Lecce, \u00e8 in programma un incontro tecnico nell\u2019ambito del progetto Interreg Italia- Grecia Cross-Border Cooperation Programme 2007-2013, <strong><em>\u201cProgetto Agroquality-Towards a Common Quality Control and Food Chain Traceability System for the Greek\u201d,<\/em> <\/strong>il cui obiettivo \u00e8 la costruzione di una piattaforma e una metodologia per il monitoraggio e la registrazione dei fattori che influenzano la quantit\u00e0 e la qualit\u00e0 delle olive de dell&#8217;olio d&#8217;oliva e il suo posizionamento nel mercato europeo e globale per migliorare le prestazioni delle piccole e medie imprese e sviluppare un modello di gestione totale .<br \/>\nAl workshop tecnico di partenariato con il quale si d\u00e0 inizio alla seconda fase di attivit\u00e0, prenderanno parte l\u2019assessore alle Politiche Comunitarie, <strong>Alessandro Delli Noci,<\/strong> il dirigente del Settore Programmazione Strategica e Comunitaria del Comune di Lecce, <strong>Raffaele Parlangeli<\/strong>, il project manager di progetto, <strong>Gianluca Pezzuto <\/strong>e il suo staff, il responsabile di Soges SPA per l&#8217;Area delle politiche pubbliche comunitarie, <strong>Andrea Gaifami,<\/strong> e una delegazione greca della quale fanno parte alcuni tecnici del Tei, Istituto Tecnologico dell\u2019Epiro, quali il project manager professor <strong>Georgios Manos<\/strong> e il capo delle attivit\u00e0 di progetto, professor <strong>Dimitrios Maretas<\/strong>.<\/p>\n<p>Venerd\u00ec 7 dicembre \u00e8 prevista una visita presso la azienda agricola Georgopolous &#8211;\u00a0 che coltiva oltre 100 ettari di superficie producendo olio extravergine di oliva e DOP &#8211; scelta come azienda-pilota del progetto.<\/p>\n<p><em>\u201cAgroquality <\/em>\u2013 afferma l\u2019assessore <strong>Alessandro Delli Noci<\/strong> \u2013<em> \u00e8 la dimostrazione di quanto i progetti comunitari, lungi dall\u2019essere mere attivit\u00e0 concettuali e privi di aspettative, vengano incontro alle esigenze e alle domande del territorio. E\u2019 nostro obiettivo primario, infatti, lavorare nell\u2019ottica del recupero e della valorizzazione dei valori mediterranei, cos\u00ec da facilitare la crescita delle imprese del territorio, migliorare la produttivit\u00e0 dell\u2019agroindustria salentina, favorire gli scambi commerciali e garantirne la competitivit\u00e0 sul piano internazionale\u201d. <\/em><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2012\/12\/06\/progetto-agroquality\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2012\/12\/06\/progetto-agroquality\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>Un workshop tecnico di partenariato si terr\u00e0 \u00a0a Lecce per parlare del progetto che punta a migliorare le prestazioni\u00a0 delle piccole e medie imprese che producono olivo d\u2019oliva. L\u2019appuntamento \u00e8 fissato per gioved\u00ec 6 dicembre, alle ore 10, ai Teatini Continua l\u2019attivit\u00e0 del Comune di Lecce nell\u2019ambito della costruzione e dello sviluppo di un modello [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":8039,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[36],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/8038"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=8038"}],"version-history":[{"count":2,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/8038\/revisions"}],"predecessor-version":[{"id":8042,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/8038\/revisions\/8042"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/8039"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=8038"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=8038"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=8038"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}