{"id":8200,"date":"2012-12-07T10:00:48","date_gmt":"2012-12-07T10:00:48","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=8200"},"modified":"2012-12-07T10:00:48","modified_gmt":"2012-12-07T10:00:48","slug":"al-voto-al-votole-ripercussioni-leccesi-delle-ultime-novita-politiche","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2012\/12\/07\/al-voto-al-votole-ripercussioni-leccesi-delle-ultime-novita-politiche\/","title":{"rendered":"AL VOTO, AL VOTO!\/Le ripercussioni leccesi delle ultime novit\u00e0 politiche"},"content":{"rendered":"<p><strong><a href=\"https:\/\/www.leccecronaca.it\/index.php\/2012\/12\/07\/al-voto-al-votole-ripercussioni-leccesi-delle-ultime-novita-politiche\/paoloperrone\/\" rel=\"attachment wp-att-8201\"><img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2012\/12\/PaoloPerrone-150x150.jpg\" alt=\"\" width=\"150\" height=\"150\" class=\"alignleft size-thumbnail wp-image-8201\" \/><\/a>(Rdl)<\/strong> Quella che era nel 1994 una gioiosa macchina da guerra, che per\u00f2 poi si rivel\u00f2 fallimentare, \u00e8 stata ricostruita per tempo dal Pd, con un\u2019operazione accorta di assemblaggio e di riverniciatura, passata sotto la lunga e perci\u00f2 ancor pi\u00f9\u00a0 utile operazione delle cos\u00ec dette \u201cprimarie\u201d. Anche a Lecce esse hanno visto buona partecipazione e hanno ottenuto il risultato di rilanciare un partito qui pi\u00f9 che altrove in difficolt\u00e0 e qui meno che altrove convinto di poter prendere il potere alle prossime elezioni.<\/p>\n<p>Dal canto suo, il Pdl vede rientrare in campo, per usare il lessico che gli \u00e8 famigliare, ma a gamba tesa, \u00e8 il caso di dirlo, e mandato da s\u00e9 stesso, allenatore e padrone, sempre per usare una metafora a lui cara, Silvio Berlusconi, il quale evidentemente non si rassegna all\u2019anonimato del \u201cpadre nobile\u201d, o al grigiore del nonno in pensione.<\/p>\n<p>Quindi niente primarie, con effetti catastrofici di immagine, di credibilit\u00e0, questi\u00a0 sicuri al momento, mentre sono tutti da ottenere e da dimostrare gli effetti benefici dell\u2019operazione, la consistenza stessa del partito, logorato da mesi di innaturale sostegno al governo Monti, di cui nessuno ha capito il senso e di presunta partecipazione gestionale, di cui nessuno ha capito il ricavo, sia per esso stesso, sia per i suoi elettori.<\/p>\n<p>A Lecce, oasi felice del Pdl, qui infatti uscito forte e compatto dalle ultime amministrative, le ripercussioni saranno inevitabili: gi\u00e0 si vedevano le linee di divisione fra il nucleo originario di \u201cForza Italia\u201d, come \u00e8 noto saldato sulle posizioni di Raffaele Fitto, e quello proveniente da \u201cAlleanza nazionale\u201d, raggruppato da Alfredo Mantovano, che a livello nazionale fa riferimento a Gianni Alemanno, fra i pi\u00f9 critici nei distinguo sugli ultimi sviluppi politici.<\/p>\n<p>A ci\u00f2 si aggiunga che della maggioranza del sindaco Paolo Perrone (nella foto, in un\u2019immagine istituzionale) fanno parte in posizione influente, anche in termini di incarichi, partiti trasformatisi in forte criticit\u00e0, come \u201cIo Sud\u201d,\u00a0 su scala nazionale divergente dal Pdl, o \u201cFuturo e libert\u00e0\u201d, che addirittura ha scelto di unirsi al polo centrista, con l\u2019Udc di Casini e il neonato movimento di Montezemolo. Insomma, neanche quando vinci forte puoi stare tranquillo, per quanto al momento non si vedano nella maggioranza leccese crepe provocate dai terremoti nazionali in atto, anche se sar\u00e0 difficile, proprio per effetto di questi, mantenerla compatta.<\/p>\n<p>Le \u201cprimarie\u201d, anzi, le \u201cparlamentarie\u201d, le hanno fatte, anzi, le stanno facendo, anche quelli del Movimento 5 Stelle, che anche a Lecce stanno scegliendo i loro rappresentanti da presentare\u00a0 al parlamento, senza la qualifica di onorevole e a stipendio autoridotto, ma con una probabile elezione di massa, visti i flussi elettorali segnalati dai sondaggi. Li stanno selezionando a modo loro, non come operazione di propaganda, o marketing politico, bens\u00ec di autorevole proposta, certo con rigore e seriet\u00e0 di metodo, visti requisiti pretesi da chi si propone e pure l\u2019attendibilit\u00e0 dei militanti che li scelgono: un sano ed innovativo esercizio di democrazia diretta, insomma.<\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2012\/12\/07\/al-voto-al-votole-ripercussioni-leccesi-delle-ultime-novita-politiche\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2012\/12\/07\/al-voto-al-votole-ripercussioni-leccesi-delle-ultime-novita-politiche\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>(Rdl) Quella che era nel 1994 una gioiosa macchina da guerra, che per\u00f2 poi si rivel\u00f2 fallimentare, \u00e8 stata ricostruita per tempo dal Pd, con un\u2019operazione accorta di assemblaggio e di riverniciatura, passata sotto la lunga e perci\u00f2 ancor pi\u00f9\u00a0 utile operazione delle cos\u00ec dette \u201cprimarie\u201d. Anche a Lecce esse hanno visto buona partecipazione e [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":8201,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[1],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/8200"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=8200"}],"version-history":[{"count":3,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/8200\/revisions"}],"predecessor-version":[{"id":8204,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/8200\/revisions\/8204"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/8201"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=8200"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=8200"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=8200"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}