{"id":83288,"date":"2016-05-03T00:07:05","date_gmt":"2016-05-02T22:07:05","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=83288"},"modified":"2016-05-02T15:49:50","modified_gmt":"2016-05-02T13:49:50","slug":"diario-del-giorno-prima-il-tam-tam-di-annibale-61","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2016\/05\/03\/diario-del-giorno-prima-il-tam-tam-di-annibale-61\/","title":{"rendered":"DIARIO DEL GIORNO PRIMA \/ IL TAM TAM DI ANNIBALE"},"content":{"rendered":"<p>ITALIA______<br \/>\nLOCRI &#8211; Arrestato boss latitante dal 2011 a Locri si \u00e8 conclusa all&#8217;alba di ieri un&#8217;importante operazione svolta dai carabinieri della citt\u00e0 calabrese insieme ai &#8220;Cacciatori antimafia&#8221;, che hanno messo fine alla latitanza di un noto pluripregiudicato di Africo Nuovo. L&#8217;arrestato, di cui l&#8217;identit\u00e0 rimane per ora secretata, deve scontare oltre vent&#8217;anni di carcere per associazione a delinquere.<\/p>\n<p><img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2016\/05\/63793382-300x214.jpg\" alt=\"\" title=\"63793382\" width=\"300\" height=\"214\" class=\"alignleft size-medium wp-image-83392\" \/>ITALIA______<br \/>\nNAPOLI &#8211; Un diciassettenne dalla fedina penale pulita, ma figlio di un capoclan del napoletano, \u00e8 stato vittima di un agguato nella citt\u00e0 partenopea. Il giovane stava percorrendo via Cavalleggeri d&#8217;Aosta a bordo di una moto, mentre due sicari lo hanno affiancato esplodendogli contro due colpi di pistola (uno dei quali lo ha raggiunto un braccio). La polizia sta indagando sui rapporti di amicizia del ferito e ricostruendo le ultime ore prima dell&#8217;attentato. Il padre del minorenne \u00e8 considerato il capo di una cosca di recente formazione.<\/p>\n<p>MONDO______<br \/>\nBOGOTA &#8211; La polizia colombiana ha reso nota la cattura di un uomo definito il trafficante di droga pi\u00f9 ricercato del Per\u00f9: Jason Galvez. E&#8217; stato fermato in un centro commerciale di Medellin. Il boss, soprannominato &#8220;Caracol&#8221;, era stato individuato a marzo in Ecuador e i suoi movimenti venivano seguiti giornalmente dai poliziotti internazionali. Galvez controlla il traffico di cocaina nella citt\u00e0 portuale di Callao ed era ricercato in patria per un centinaio di omicidi. Attualmente e&#8217; forse il narcotrafficante pi\u00f9 potente al mondo.<\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2016\/05\/03\/diario-del-giorno-prima-il-tam-tam-di-annibale-61\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2016\/05\/03\/diario-del-giorno-prima-il-tam-tam-di-annibale-61\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>ITALIA______ LOCRI &#8211; Arrestato boss latitante dal 2011 a Locri si \u00e8 conclusa all&#8217;alba di ieri un&#8217;importante operazione svolta dai carabinieri della citt\u00e0 calabrese insieme ai &#8220;Cacciatori antimafia&#8221;, che hanno messo fine alla latitanza di un noto pluripregiudicato di Africo Nuovo. L&#8217;arrestato, di cui l&#8217;identit\u00e0 rimane per ora secretata, deve scontare oltre vent&#8217;anni di carcere [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":83392,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[1,69,76],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/83288"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=83288"}],"version-history":[{"count":2,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/83288\/revisions"}],"predecessor-version":[{"id":83393,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/83288\/revisions\/83393"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/83392"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=83288"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=83288"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=83288"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}