{"id":84816,"date":"2016-05-16T11:56:45","date_gmt":"2016-05-16T09:56:45","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=84816"},"modified":"2016-05-16T16:23:11","modified_gmt":"2016-05-16T14:23:11","slug":"sulamente-a-nna-cosa-nu-nce-rimediu-unesilarante-commedia-novolese-nel-ricordo-del-maestro-mario-teni","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2016\/05\/16\/sulamente-a-nna-cosa-nu-nce-rimediu-unesilarante-commedia-novolese-nel-ricordo-del-maestro-mario-teni\/","title":{"rendered":"&#8220;SULAMENTE A NNA COSA NU NC&#8217;E&#8217; RIMEDIU&#8221; \/ UN&#8217;ESILARANTE COMMEDIA NOVOLESE NEL RICORDO DEL MAESTRO MARIO TENI"},"content":{"rendered":"<p>di<strong> Annibale Gagliani______<\/strong><\/p>\n<p><img decoding=\"async\" loading=\"lazy\" width=\"300\" height=\"168\" title=\"20160515_204738\" class=\"alignleft size-medium wp-image-84817\" alt=\"\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2016\/05\/20160515_204738-300x168.jpg\" \/>Ecco la paura pi\u00f9 grande dell&#8217;uomo, quella variabile impazzita che non potr\u00e0 mai controllare n\u00e9 con sprazzi di magia e nemmeno con le ultime diavolerie cibernetiche: &#8220;Sulamente a nna cosa nu nc&#8217;\u00e8 rimediu&#8221;\u2026 giustappunto.<\/p>\n<p>Dalla fantasia fresca e armonica del giovane autore teatrale Mario Secl\u00ec, nasce quest&#8217;opera comica in vernacolo novolese, che di certo non vuole essere un elogio dell&#8217;ultimo atto dell&#8217;esistenza umana, ma uno spassionato invito a indagare nell&#8217;animo di ognuno di noi per ricercare il tanto decantato &#8220;life sense&#8221;.<\/p>\n<p>La talentuosa compagnia teatrale <em>&#8220;Mario Teni&#8221;<\/em>, che dedica il proprio nome al maestro <em>Teni<\/em>, esponente di assoluto valore nel panorama commediografo salentino, si \u00e8 ripetuta a grande richiesta per la terza volta nell&#8217;accogliente Teatrino Parrocchiale &#8220;Santa Maria Del Pane&#8221;.<\/p>\n<p>15 maggio 2016, il pubblico pagante di sbellicava dalle risate sbeffeggiando i tormenti della protagonista &#8220;Ronzina&#8221; (Paola Errico) sicura di essere vicina alla morte dopo averne avuto uno strano presentimento in sogno. Povero marito &#8220;Gianni&#8221; (Alessandro De Tommasi) e povera figlia &#8220;Vincenza&#8221; (Dalila Arnesano), che dovranno sopportare nel tam tam giornaliero le tiritere lamentose della padrona di casa, intenta a organizzare nei minimi dettagli il tanto atteso giorno del suo funerale.<img decoding=\"async\" loading=\"lazy\" width=\"300\" height=\"168\" title=\"20160515_205122\" class=\"alignright size-medium wp-image-84818\" alt=\"\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2016\/05\/20160515_205122-300x168.jpg\" \/><\/p>\n<p>Addirittura la modaiola &#8220;Giusy&#8221; (Francesca Santo) amica del cuore di Vincenza, si burler\u00e0 dei macabri pensieri di donna Ronzina, che sempre pi\u00f9 in preda ale cattive visioni, giusto per &#8220;ammazzare&#8221; il tempo, si perde tra un caff\u00e8 con le &#8220;comari beatille&#8221;, una messa da novolese opinion leader e diverse lezioni tragicomiche sull&#8217;uso di Facebook. Arriva un nuovo amore nella sventurata dimora a scombinare l&#8217;ansimante routine: Rominu (Cesare Secl\u00ec) che chiede la mano di Vincenza ai suoi genitori. Lei naturalmente acconsente, ma \u00e8 terrorizzata dall&#8217;idea di un incontro di fuoco tra il moroso e l&#8217;integerrimo padre. Rominu \u00e8 la punta di diamante dell&#8217;agenzia funebre della sua famiglia, piccolo particolare che far\u00e0 cadere nel cieco sconforto Gianni dopo aver appreso la notizia.<\/p>\n<p><img decoding=\"async\" loading=\"lazy\" width=\"300\" height=\"168\" title=\"20160515_212958\" class=\"alignleft size-medium wp-image-84819\" alt=\"\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2016\/05\/20160515_212958-300x168.jpg\" \/>Compare Pascalinu (Vincenzo Sebaste) sar\u00e0 il primo a grattarsi gli attributi (come rito scaccia-morte) dopo la confessione del padre disperato, che sa gi\u00e0 di dover attirare tutte le congetture superstiziose del circolo paesano. Ma l&#8217;amore trionfa su tutto! E il babbo e la &#8220;morente mamma&#8221; lo capiranno presto. Daranno un pass al sapore di aglio alla propria figlia che potr\u00e0 finalmente amare il suo ragazzo senza la paura di essere malmenata per casa. I tre atti dell&#8217;opera scorrono su un&#8217;unica scenografia d&#8217;interno (costruita da Alessandro Calabrese e Francesco Bacca) che assieme al rilievo centrale che si d\u00e0 al dialetto ricorda molto il teatro del dopoguerra di Eduardo De Filippo: semplice, efficace e che fa riflettere la notte sotto le coperte. La commedia si serve di una figura storica del panorama teatrale non sempre pi\u00f9 utilizzata, il suggeritore (per l&#8217;occasione saranno tre Giuseppe Falangone, Massimo Vetrugno e Luigina Bisconti).<\/p>\n<p>Il dialogo ancestrale tra la protagonista Ronzina e &#8220;La Morte&#8221; (interpretata in uno scenario mistico da Stefania De Luca), regala un pugno di domande all&#8217;osservatore, chiamato a indagare sul proprio sentiero. Siete egoisti? Non regalate nemmeno cinque minuti del vostro tempo al prossimo? Avete almeno una volta donato tanto amore, ma talmente tanto, che nemmeno una vostra improvvisa dipartita lo potr\u00e0 cancellare? <img decoding=\"async\" loading=\"lazy\" width=\"300\" height=\"168\" title=\"20160515_211505\" class=\"alignright size-medium wp-image-84820\" alt=\"\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2016\/05\/20160515_211505-300x168.jpg\" \/><\/p>\n<p>Ovviamente io mi auguro di si, come mi auguro che andrete a vedere la prossima replica di &#8220;Sulamente a nna cosa nu nc&#8217;\u00e8 rimediu&#8221;, poich\u00e9 questo giovane lavoro di scena \u00e8 umile, piacevole e molto intellegibile. Soprattutto voi novolesi segnatevi questi due nomi: Mario Secl\u00ec e Cesare Secl\u00ec, vi assicuro che saranno la risposta tutta salentina alle leggendarie Gemelle Kessler.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p><em>&#8220;Nella vita c&#8217;\u00e8 una cosa sola che non dice le bugie: a&#8217; morte&#8230;&#8221;.<\/em><\/p>\n<p><strong>Edurardo De Filippo<\/strong><\/p>\n<p><img decoding=\"async\" loading=\"lazy\" width=\"1024\" height=\"576\" title=\"20160515_224704\" class=\"aligncenter size-large wp-image-84821\" alt=\"\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2016\/05\/20160515_224704-1024x576.jpg\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2016\/05\/20160515_224704-1024x576.jpg 1024w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2016\/05\/20160515_224704-300x169.jpg 300w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2016\/05\/20160515_224704-768x432.jpg 768w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2016\/05\/20160515_224704-1536x864.jpg 1536w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2016\/05\/20160515_224704-2048x1152.jpg 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2016\/05\/16\/sulamente-a-nna-cosa-nu-nce-rimediu-unesilarante-commedia-novolese-nel-ricordo-del-maestro-mario-teni\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2016\/05\/16\/sulamente-a-nna-cosa-nu-nce-rimediu-unesilarante-commedia-novolese-nel-ricordo-del-maestro-mario-teni\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>di Annibale Gagliani______ Ecco la paura pi\u00f9 grande dell&#8217;uomo, quella variabile impazzita che non potr\u00e0 mai controllare n\u00e9 con sprazzi di magia e nemmeno con le ultime diavolerie cibernetiche: &#8220;Sulamente a nna cosa nu nc&#8217;\u00e8 rimediu&#8221;\u2026 giustappunto. Dalla fantasia fresca e armonica del giovane autore teatrale Mario Secl\u00ec, nasce quest&#8217;opera comica in vernacolo novolese, che [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":84821,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[1,31,75],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/84816"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=84816"}],"version-history":[{"count":4,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/84816\/revisions"}],"predecessor-version":[{"id":84823,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/84816\/revisions\/84823"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/84821"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=84816"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=84816"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=84816"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}