{"id":8559,"date":"2012-12-12T15:52:52","date_gmt":"2012-12-12T15:52:52","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=8559"},"modified":"2012-12-12T15:55:30","modified_gmt":"2012-12-12T15:55:30","slug":"europrogettisti-cercasi","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2012\/12\/12\/europrogettisti-cercasi\/","title":{"rendered":"EUROPROGETTISTI CERCASI"},"content":{"rendered":"<p><strong><em><a href=\"https:\/\/www.leccecronaca.it\/index.php\/2012\/12\/12\/europrogettisti-cercasi\/universitari_italiani_pessimisti_sul_futuro_e_preoccupati_per_il_carovita\/\" rel=\"attachment wp-att-8562\"><img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2012\/12\/universitari_italiani_pessimisti_sul_futuro_e_preoccupati_per_il_carovita-150x150.jpg\" alt=\"\" width=\"150\" height=\"150\" class=\"alignleft size-thumbnail wp-image-8562\" \/><\/a>E\u2019 stato pubblicato il bando Leonardo Da Vinci \u201cYou4Eu\u201d per i giovani residenti in provincia di Lecce. <\/em><\/strong><strong><em>Il tirocinio formativo\u00a0\u00a0 ha\u00a0\u00a0 una\u00a0\u00a0 durata\u00a0\u00a0 di\u00a0\u00a0 12 settimane. \u00a0C\u2019\u00e8 tempo fino al 15 dicembre per presentare le candidature<br \/>\n<\/em><\/strong>L&#8217;Associazione Work in Progress forma 36 europrogettisti per lo sviluppo territoriale. Pubblicato il Bando \u201cLeonardo Da Vinci You4Eu&#8221;. E&#8217; l&#8217;unico\u00a0 progetto\u00a0 approvato\u00a0 in Puglia dall&#8217;ISFOL, Agenzia Nazionale\u00a0 di\u00a0 Coordinamento\u00a0 del Programma\u00a0\u00a0 Lifelong Learning &#8211; Leonardo da Vinci &#8211; Azione\u00a0 PLM People\u00a0 on Labour Market, dedicato a 36 giovani diplomati o laureati disponibili sul mercato del lavoro e residenti nella Provincia di Lecce.<\/p>\n<p>Il tirocinio formativo ha una durata di 12 settimane nel campo della gestione di progetti Europei e management delle associazioni. Il 20% dei posti \u00e8 riservato ai giovani sordi dell&#8217;Associazione AEEOS e ENS di Lecce.<\/p>\n<p>Il progetto <strong>&#8220;You4Eu: Management of NGOs for Inclusive Growth<\/strong>&#8221; nasce dall&#8217;esigenza di diffondere nella Provincia di Lecce una cultura europea che renda i giovani consapevoli delle opportunit\u00e0 di apprendimento non formale e di crescita che questo offre per lo sviluppo personale e professionale, finalizzati all&#8217;inserimento lavorativo e allo sviluppo dell&#8217; imprenditorialit\u00e0 giovanile.<\/p>\n<p>Il progetto si focalizza sul Management del Terzo Settore, che attualmente, richiede competenze tecniche, manageriali e contabili sempre pi\u00f9 ricercate per poter cogliere al meglio le molteplici opportunit\u00e0 di finanziamento in un contesto lavorativo europeo.<\/p>\n<p>L&#8217;associazione Work in Progress si avvale di un forte partenariato territoriale sia per il coordinamento del progetto You4eu, sia per l&#8217;inserimento degli stagisti nelle strutture partner per ulteriori 2 mesi al fine di implementare nella Provincia di Lecce le competenze manageriali acquisite all&#8217;estero.<\/p>\n<p>I partner attivi in tutte le fasi del progetto sono: il Comune di Lecce, le Officine Cantelmo di Lecce, Polaris Consulting di Galatone, il GAL Isola Salento di Martano, l&#8217;associazione AEEOS e ENS &#8211; Ente Nazionale Sordi di Lecce, l&#8217;Associazione Millepiedi e Comune di Giuggianello e 1&#8217;Associazione Jump in di Poggiardo.<\/p>\n<p><strong>Lo stage si svolger\u00e0 nei mesi di febbraio-luglio 2013<\/strong> nei seguenti Paesi partner: Portogallo, Spagna, Francia, Olanda, Belgio, Turchia, Romania, Irlanda e Rep. Ceca, tutti con consolidata esperienza nel campo della progettazione Europea e quindi in grado di offrire un periodo di stage di 3 mesi di alto contenuto formativo e di esperienza sul campo.<\/p>\n<p><strong>Calendario<\/strong> Fasi Progetto:<\/p>\n<p>&nbsp;<\/p>\n<table border=\"0\" cellspacing=\"0\" cellpadding=\"0\">\n<tbody>\n<tr>\n<td valign=\"top\" width=\"233\"><strong>26 Novembre 2012<\/strong><\/td>\n<td valign=\"top\" width=\"235\"><strong>Pubblicazione Bando You4Eu<\/strong><\/td>\n<\/tr>\n<tr>\n<td valign=\"top\" width=\"233\"><strong>10 Dicembre 2012<\/strong><\/td>\n<td valign=\"top\" width=\"235\">\n<p align=\"center\"><strong>InfoDay You4eu a Lecce (controllare il sito per<\/strong><\/p>\n<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>&nbsp;<\/p>\n<p><strong>Ora\u00a0 e luogo<\/strong><\/p>\n<table border=\"0\" cellspacing=\"0\" cellpadding=\"0\">\n<tbody>\n<tr>\n<td valign=\"top\" width=\"233\"><strong>15 Dicembre 2012<\/strong><\/td>\n<td valign=\"top\" width=\"234\"><strong>Chiusura Bando You4Eu<\/strong><\/td>\n<\/tr>\n<tr>\n<td valign=\"top\" width=\"233\"><strong>19 Dicembre 2012<\/strong><\/td>\n<td valign=\"top\" width=\"234\"><strong>Pubblicazione Graduatoria Pre-selezione<\/strong><\/td>\n<\/tr>\n<tr>\n<td valign=\"top\" width=\"233\"><strong>21 Dicembre 2012<\/strong><\/td>\n<td valign=\"top\" width=\"234\"><strong>Colloqui Individuali<\/strong><\/td>\n<\/tr>\n<tr>\n<td valign=\"top\" width=\"233\"><strong>23 Dicembre 2012<\/strong><\/td>\n<td valign=\"top\" width=\"234\"><strong>Pubblicazione Graduatoria Definitiva<\/strong><\/td>\n<\/tr>\n<tr>\n<td valign=\"top\" width=\"233\"><strong>Gennaio 2013<\/strong><\/td>\n<td valign=\"top\" width=\"234\"><strong>Formazione Pre-Partenza (5 giornate)<\/strong><\/td>\n<\/tr>\n<tr>\n<td valign=\"top\" width=\"233\"><strong>1 Febbraio -1 Maggio 2013<\/strong><\/td>\n<td valign=\"top\" width=\"234\"><strong>Partenza <\/strong><strong>I <\/strong><strong>Flusso -18 assegnatari<\/strong><\/td>\n<\/tr>\n<tr>\n<td valign=\"top\" width=\"233\"><strong>1 Maggio -1 Agosto 2013<\/strong><\/td>\n<td valign=\"top\" width=\"234\"><strong>Partenza <\/strong><strong>II <\/strong><strong>Flusso -18 assegnatari<\/strong><\/td>\n<\/tr>\n<tr>\n<td valign=\"top\" width=\"233\"><strong>Maggio &#8211; Settembre 2013<\/strong><\/td>\n<td valign=\"top\" width=\"234\"><strong>Stage presso i Partner Intermediari<\/strong><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p><strong>Requisiti<\/strong> minimi di accesso alla Borsa Leonardo sono:<\/p>\n<ol>\n<li>Essere residenti a Lecce o Provincia di Lecce da almeno un anno;\n<ol>\n<li>Et\u00e0 compresa tra 23 e 33 anni (alla data di scadenza del bando il candidato non deve aver compiuto i 34 anni);<\/li>\n<li>Essere Cittadini Italiani o possedere la Cittadinanza di uno dei Paesi dell&#8217;Unione Europea con residenza regolare in Italia;<\/li>\n<li>Essere in possesso di qualifica professionale, o di Diploma di Laurea e non essere iscritti a nessun percorso di studi Universitario, n\u00e9 Master, dottorato o altri corsi di formazione;<\/li>\n<li>Buona conoscenza della lingua inglese. Il livello di conoscenza linguistica sar\u00e0 comunque valutato in fase di colloquio di selezione;<\/li>\n<li>Non aver mai beneficiato di altre Borse di mobilit\u00e0 finanziate dal programma Leonardo da Vinci nella misura PLM &#8211; People in the Labour Market;<\/li>\n<\/ol>\n<\/li>\n<\/ol>\n<p>&nbsp;<\/p>\n<p>La<strong> scadenza <\/strong>per far pervenire le candidature \u00e8 fissata per il giorno 15 dicembre 2012.<\/p>\n<p><strong>Contatti<\/strong>: dottoressa Marzia Stenti, coordinatrice LLP (e-mail: <span style=\"text-decoration: underline\"><a href=\"mailto:leonardo@workinprogress-wip.eu\">leonardo@workinprogress-wip.eu<\/a><\/span><span style=\"text-decoration: underline\">; <\/span>telefono: 0832 323153, dal luned\u00ec al venerd\u00ec 10-13)<\/p>\n<p>Per <strong>informazioni <\/strong>generali sul progetto:<\/p>\n<ol>\n<li>Informazioni e modulistica: <span style=\"text-decoration: underline\"><a href=\"http:\/\/www.workinprogress-wip.eu\">www.workinprogress-wip.eu<\/a><\/span> e via newsletter<\/li>\n<li>Informazioni generali: Pagina facebook <span style=\"text-decoration: underline\">You4Eu<\/span><\/li>\n<\/ol>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2012\/12\/12\/europrogettisti-cercasi\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2012\/12\/12\/europrogettisti-cercasi\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>E\u2019 stato pubblicato il bando Leonardo Da Vinci \u201cYou4Eu\u201d per i giovani residenti in provincia di Lecce. Il tirocinio formativo\u00a0\u00a0 ha\u00a0\u00a0 una\u00a0\u00a0 durata\u00a0\u00a0 di\u00a0\u00a0 12 settimane. \u00a0C\u2019\u00e8 tempo fino al 15 dicembre per presentare le candidature L&#8217;Associazione Work in Progress forma 36 europrogettisti per lo sviluppo territoriale. Pubblicato il Bando \u201cLeonardo Da Vinci You4Eu&#8221;. E&#8217; [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":8562,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[1],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/8559"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=8559"}],"version-history":[{"count":4,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/8559\/revisions"}],"predecessor-version":[{"id":8564,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/8559\/revisions\/8564"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/8562"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=8559"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=8559"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=8559"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}