{"id":8572,"date":"2012-12-12T17:02:47","date_gmt":"2012-12-12T17:02:47","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=8572"},"modified":"2012-12-12T17:02:47","modified_gmt":"2012-12-12T17:02:47","slug":"nick-sul-trampolino-di-lancio-verso-il-successo-scopriamo-il-concorrente-salentino-di-amici","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2012\/12\/12\/nick-sul-trampolino-di-lancio-verso-il-successo-scopriamo-il-concorrente-salentino-di-amici\/","title":{"rendered":"NICK SUL TRAMPOLINO DI LANCIO VERSO IL SUCCESSO \/ SCOPRIAMO IL CONCORRENTE SALENTINO DI &#8220;AMICI&#8221;"},"content":{"rendered":"<p><a href=\"https:\/\/www.leccecronaca.it\/index.php\/2012\/12\/12\/nick-sul-trampolino-di-lancio-verso-il-successo-scopriamo-il-concorrente-salentino-di-amici\/nicola-rosafio\/\" rel=\"attachment wp-att-8573\"><img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2012\/12\/Nicola-Rosafio-150x150.jpg\" alt=\"\" width=\"150\" height=\"150\" class=\"alignleft size-thumbnail wp-image-8573\" \/><\/a>Un ragazzo di 22 anni che si presenta saltellando ai provini del noto talent show \u201cAmici di Maria De Filippi\u201d, e davanti al pubblico, in studio e televisivo, come frase di presentazione esclama \u201cDevo fare pip\u00ec!\u201d, di certo non passa inosservato. \u00c8 il caso del salentino Nicola Rosafio, proveniente da Acquarica del Capo, professione cantante, che \u00e8 in lizza per un banco nella scuola televisiva pi\u00f9 famosa della penisola. Nicola sa il fatto suo: spigliato e sicuro davanti alle telecamere, si \u00e8 esibito per la prima volta su Canale 5 lo scorso 24 novembre, presentando una canzone di Adriano Celentano, \u201cCiao ragazzi\u201d.<\/p>\n<p>Fin troppo disinvolto, ha condito la sua performance con eccessiva mimica facciale: gesti e saluti al pubblico, e per l\u2019insegnante Grazia Di Michele, che l\u2019ha trovato tecnicamente carente, non era meritevole di entrare nella scuola.<\/p>\n<p>Tuttavia il ragazzo ha un angelo custode di nome Rudy Zerbi, il quale ha apprezzato il carisma di \u201cNick\u201d (come \u00e8 gi\u00e0 stato soprannominato nelle varie pagine dei social network dedicato a lui) e gli ha consentito di proseguire il suo cammino, nell\u2019attesa delle prossime puntate in cui scopriremo se sar\u00e0 uno dei concorrenti effettivi del programma, che \u00e8 ancora in fase di selezioni.<\/p>\n<p>Insomma, un bel trampolino di lancio per Nicola, che ora \u00e8 in trepidante attesa di sapere se potr\u00e0 o meno entrare a far parte della scuola.<\/p>\n<p>Nel suo video di presentazione ha confessato che \u201c<em>cantare gli piace quasi quanto fare l\u2019amore<\/em>\u201d; nonostante si sia presentato come cantante, ha avuto anche delle esperienze in altre discipline artistiche, in particolare ha preso lezioni di danza classica e di recitazione, partecipando a uno stage nel 2010 presso la Compagnia della Rancia a Roma, la pi\u00f9 importante compagnia di musical italiana. Per coronare il tutto, Nicola al momento \u00e8 anche uno studente universitario: \u00e8 infatti iscritto alla facolt\u00e0 di giurisprudenza presso l\u2019Universit\u00e0 del Salento. A lui, a tutti gli abitanti di Acquarica del Capo che fanno il tifo per lui, e a tutti i suoi fan sparsi per l\u2019Italia, non resta che aspettare le prossime puntate per scoprire se Nicola far\u00e0 parte o meno del talent show: in tal caso ancora una volta il Salento avrebbe un suo rappresentante in una delle realt\u00e0 televisive giovanili pi\u00f9 famose e fortunate nel nostro paese, cos\u00ec come l\u2019anno scorso \u00e8 stato per Claudia Casciaro, di Marittima, e Marco Castelluzzo di Tricase, entrambi in provincia di Lecce.<\/p>\n<p><strong>Bianca Chiriatti<\/strong><\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2012\/12\/12\/nick-sul-trampolino-di-lancio-verso-il-successo-scopriamo-il-concorrente-salentino-di-amici\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2012\/12\/12\/nick-sul-trampolino-di-lancio-verso-il-successo-scopriamo-il-concorrente-salentino-di-amici\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>Un ragazzo di 22 anni che si presenta saltellando ai provini del noto talent show \u201cAmici di Maria De Filippi\u201d, e davanti al pubblico, in studio e televisivo, come frase di presentazione esclama \u201cDevo fare pip\u00ec!\u201d, di certo non passa inosservato. \u00c8 il caso del salentino Nicola Rosafio, proveniente da Acquarica del Capo, professione cantante, [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":8573,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[1],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/8572"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=8572"}],"version-history":[{"count":3,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/8572\/revisions"}],"predecessor-version":[{"id":8577,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/8572\/revisions\/8577"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/8573"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=8572"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=8572"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=8572"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}