{"id":86887,"date":"2016-06-06T15:28:45","date_gmt":"2016-06-06T13:28:45","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=86887"},"modified":"2016-06-06T18:58:21","modified_gmt":"2016-06-06T16:58:21","slug":"a-cavallino-sconfitta-la-politica-del-pd-provinciale","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2016\/06\/06\/a-cavallino-sconfitta-la-politica-del-pd-provinciale\/","title":{"rendered":"A CAVALLINO SCONFITTA LA POLITICA DEL PD PROVINCIALE &#8211; All&#8217;interno i voti di lista e le preferenze di tutti i candidati"},"content":{"rendered":"\n\t\t<style type=\"text\/css\">\n\t\t\t#gallery-1 {\n\t\t\t\tmargin: auto;\n\t\t\t}\n\t\t\t#gallery-1 .gallery-item {\n\t\t\t\tfloat: left;\n\t\t\t\tmargin-top: 10px;\n\t\t\t\ttext-align: center;\n\t\t\t\twidth: 100%;\n\t\t\t}\n\t\t\t#gallery-1 img {\n\t\t\t\t\n\t\t\t}\n\t\t\t#gallery-1 .gallery-caption {\n\t\t\t\tmargin-left: 0;\n\t\t\t}\n\t\t\t\/* see gallery_shortcode() in wp-includes\/media.php *\/\n\t\t<\/style>\n\t\t<div id='gallery-1' class='gallery galleryid-86887 gallery-columns-1 gallery-size-thumbnail'><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2016\/06\/4.jpg'><img width=\"150\" height=\"150\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2016\/06\/4-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" decoding=\"async\" loading=\"lazy\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2016\/06\/4-150x150.jpg 150w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2016\/06\/4-60x60.jpg 60w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/><\/a>\n\t\t\t<\/dt><\/dl><br style=\"clear: both\" \/><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2016\/06\/31.jpg'><img width=\"150\" height=\"150\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2016\/06\/31-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" decoding=\"async\" loading=\"lazy\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2016\/06\/31-150x150.jpg 150w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2016\/06\/31-60x60.jpg 60w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/><\/a>\n\t\t\t<\/dt><\/dl><br style=\"clear: both\" \/><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2016\/06\/2.jpg'><img width=\"150\" height=\"150\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2016\/06\/2-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" decoding=\"async\" loading=\"lazy\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2016\/06\/2-150x150.jpg 150w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2016\/06\/2-60x60.jpg 60w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/><\/a>\n\t\t\t<\/dt><\/dl><br style=\"clear: both\" \/><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2016\/06\/1.jpg'><img width=\"150\" height=\"150\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2016\/06\/1-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" decoding=\"async\" loading=\"lazy\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2016\/06\/1-150x150.jpg 150w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2016\/06\/1-60x60.jpg 60w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/><\/a>\n\t\t\t<\/dt><\/dl><br style=\"clear: both\" \/>\n\t\t<\/div>\n\n<p>(v.m.)_______CAVALLINO: Subisce una cocente sconfitta la lista Futuro e Democrazia con Carla Rugge Sindaco 2533 voti, appoggiata ufficialmente dal Partito Democratico, da Forza Italia, dalla Puglia in Pi\u00f9 del Senatore Stefano, oltre che da altri soggetti politici, come la proposta di &#8220;Possibile&#8221; il gruppo di sinistra che fa riferimento Civati, ed il partito dell&#8217;UDC che fa riferimento al Senatore Ruggeri, che con uno scarto di quasi 1500 voti, viene battuta da Bruno Ciccarese della lista Gorgoni Sindaco che prende 3965 voti.<br \/>\nA Cavallino la Segreteria provinciale ha deciso di spaccare il partito mettendo fuori gioco il gruppo storico del PD, pur di candidare a Sindaco Carla Rugge, gi\u00e0 Consigliere comunale di Alleanza Nazionale, e poi pi\u00f9 volte candidata nella Lista Gorgoni Sindaco, sedendo e ricoprendo ruoli istituzionali nella compagine gorgoniana.<br \/>\nEcco, secondo lo stato maggiore del Pd, il rinnovamento poteva essere rappresentato da una candidata che aveva condiviso per oltre un decennio la politica del ras di Cavallino.<br \/>\nOvviamente cos\u00ec non poteva essere e cos\u00ec non \u00e8 stato.<br \/>\nEd a nulla \u00e8 servito far scendere in campo i boss del partito e le truppe cammellate, \u00e8 stato scomodato persino il Presidente della Regione Puglia \u00a0Emiliano che \u00e8 andato a Cavallino dove ha tenuto un comizio in sostegno della Rugge.<\/p>\n<p>La terza lista in campo, quella del Movimento 5 Stelle, non ha saputo approfittare della spaccatura del PD, e non \u00e8 riuscita a mobilitare i tanti cittadini cavallinesi che pure da anni sono iscritti al movimento, per cui si \u00e8 dovuta accontentare di portare a casa 1046 voti.<br \/>\nMorale della favola, una volta La lista Gorgoni vinceva perch\u00e9, Forza Italia pubblicamente ed il PD sottobanco la appoggiavano, oggi vince perch\u00e9 questi due partiti non trovano di meglio che candidare come volto nuovo della politica, una persona che con Gorgoni e company ha condiviso scelte politiche e modo di amministrare.<\/p>\n<p>Insomma la lista di Carla Rugge era un minestrone male assortito, e i cittadini non lo hanno gradito, a chi lo ha preparato credo che rester\u00e0 sullo stomaco per un po&#8217; di tempo.<\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2016\/06\/06\/a-cavallino-sconfitta-la-politica-del-pd-provinciale\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2016\/06\/06\/a-cavallino-sconfitta-la-politica-del-pd-provinciale\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>(v.m.)_______CAVALLINO: Subisce una cocente sconfitta la lista Futuro e Democrazia con Carla Rugge Sindaco 2533 voti, appoggiata ufficialmente dal Partito Democratico, da Forza Italia, dalla Puglia in Pi\u00f9 del Senatore Stefano, oltre che da altri soggetti politici, come la proposta di &#8220;Possibile&#8221; il gruppo di sinistra che fa riferimento Civati, ed il partito dell&#8217;UDC che [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[76],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/86887"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=86887"}],"version-history":[{"count":14,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/86887\/revisions"}],"predecessor-version":[{"id":86889,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/86887\/revisions\/86889"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=86887"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=86887"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=86887"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}