{"id":8819,"date":"2012-12-17T13:51:08","date_gmt":"2012-12-17T13:51:08","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=8819"},"modified":"2013-01-15T08:14:18","modified_gmt":"2013-01-15T08:14:18","slug":"la-costituzione-secondo-i-ragazzi-articolo-2","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2012\/12\/17\/la-costituzione-secondo-i-ragazzi-articolo-2\/","title":{"rendered":"[La Costituzione secondo i ragazzi] Articolo 2"},"content":{"rendered":"<p><a href=\"https:\/\/www.leccecronaca.it\/index.php\/2012\/12\/17\/la-costituzione-secondo-i-ragazzi-articolo-2\/arton4909\/\" rel=\"attachment wp-att-8822\"><img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2012\/12\/arton4909-150x150.jpg\" alt=\"\" width=\"150\" height=\"150\" class=\"alignleft size-thumbnail wp-image-8822\" \/><\/a>Articolo 2: \u201cLa Repubblica riconosce e garantisce i diritti inviolabili dell&#8217;uomo, sia come singolo sia nelle formazioni sociali ove si svolge la sua personalit\u00e0, e richiede l&#8217;adempimento dei doveri inderogabili di solidariet\u00e0 politica, economica e sociale\u201d<br \/>\nNel secondo articolo della Costituzione, la Repubblica italiana fa riferimento a un tipo di diritti che storicamente fecero la loro prima comparsa ufficiale nella Dichiarazione dei diritti dell\u2019uomo e del cittadino, un documento stilato a Parigi nel 1789, al termine della Rivoluzione francese.<br \/>\nLo scopo di questa dichiarazione era creare una base di diritti fondamentali da inserire poi nella Carta Costituzionale, come segno definitivo del passaggio dall\u2019Ancien R\u00e9gime a una monarchia costituzionale. Fu un documento rivoluzionario non solo perch\u00e9 avveniva alla fine di un evento destinato a cambiare le coscienze di molti popoli, ma perch\u00e9 per primo defin\u00ec una serie di \u201cdiritti naturali ed imperscrittibili dell\u2019uomo\u201d che avrebbero ispirato non solo tutte le Costituzioni che sarebbero state redatte successivamente, ma anche la Dichiarazione universale dei diritti dell\u2019uomo adottata dall\u2019ONU nel 1948. Questo tipo di diritti non appartenevano pi\u00f9 all\u2019uomo in quanto cittadino, ma la loro esistenza era precedente e pi\u00f9 importante di quella dello Stato.<br \/>\nCos\u00ec avviene nella nostra Costituzione, che si riferisce a questa concezione di diritti che lo Stato riconosce e si impegna a garantire attraverso dei doveri inderogabili. Sono compresi quindi in questa definizione i concetti fondamentali di eguaglianza, libert\u00e0 di parola, di fede e di opinione e molti altri che saranno poi singolarmente esaminati nel corso della Costituzione.<br \/>\nIl principio espresso nel secondo articolo \u00e8 spesso definito \u201cpersonalista\u201d, poich\u00e9 riconosce il valore dell\u2019individuo, considerando anche ogni ambito in cui esso manifesta la sua personalit\u00e0: all\u2019interno della famiglia, del posto di lavoro, delle associazioni, dei luoghi di culto.<br \/>\nSi tratta di uno dei principi pi\u00f9 profondi della nostra Costituzione, poich\u00e9 riguarda ognuno di noi nella sua persona, ma allo stesso tempo ci mette davanti a una grande responsabilit\u00e0 nei confronti dell\u2019altro. I doveri di \u201csolidariet\u00e0 politica, economica e sociale\u201d derivano strettamente dai diritti inviolabili che ci appartengono, costituendo quindi la spinta per una propria realizzazione all\u2019interno di una societ\u00e0 libera e fatta di pari opportunit\u00e0 che per\u00f2 noi stessi, insieme allo Stato, dobbiamo costruire. \u00c8 questo il significato del \u201cprincipio personalista\u201d: non una concezione individualista della societ\u00e0, ma piuttosto una responsabilit\u00e0 comune, che il secondo articolo sancisce ufficialmente come base stessa del funzionamento dei rapporti tra gli uomini, e quindi di quello Stato.<br \/>\nCome la Dichiarazione dei diritti dell\u2019uomo e del cittadino segn\u00f2 la volont\u00e0 di voltare le spalle alla monarchia assoluta, anche nel caso della nostra Costituzione questo articolo \u00e8 quello che meglio incarna la svolta totale che si voleva dare all\u2019Italia dopo la dittatura fascista. Dopo anni di terrore e di sangue, gli italiani avevano bisogno di vedere i diritti dell\u2019essere umano riconosciuti e difesi dallo Stato, quello stesso Stato che li aveva messi da parte durante la guerra.<br \/>\nE se il secondo articolo ha avuto un\u2019importanza simbolica inestimabile nel periodo in cui fu scritto, di sicuro non ha perso la sua attualit\u00e0 neanche al giorno d\u2019oggi. Innanzitutto, esso ha reso possibile l\u2019evoluzione della Costituzione stessa nel passare degli anni, attraverso l\u2019inserimento di nuovi articoli in difesa di nuovi diritti che hanno fatto la loro comparsa successivamente. Pensiamo alla tutela dell\u2019ambiente, al diritto all\u2019abitazione, alla privacy, ma anche alle trasformazioni dei diritti che hanno acquisito un significato differente in tempi moderni.<br \/>\nE\u2019 per questo infatti, che di fronte alla situazione critica di molti Paesi del mondo, in cui i diritti non solo non vengono riconosciuti, ma addirittura sono calpestati da guerre o condizioni di vita estreme, che essi diventano oggetto di continua analisi e discussione e continuano a costituire la parte viva e in evoluzione della nostra Costituzione.<\/p>\n<p>Claudia Rizzo<br \/>\nper Il Sottobanco,<br \/>\nrubrica a cura di Rachele Caracciolo<\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2012\/12\/17\/la-costituzione-secondo-i-ragazzi-articolo-2\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2012\/12\/17\/la-costituzione-secondo-i-ragazzi-articolo-2\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>Articolo 2: \u201cLa Repubblica riconosce e garantisce i diritti inviolabili dell&#8217;uomo, sia come singolo sia nelle formazioni sociali ove si svolge la sua personalit\u00e0, e richiede l&#8217;adempimento dei doveri inderogabili di solidariet\u00e0 politica, economica e sociale\u201d Nel secondo articolo della Costituzione, la Repubblica italiana fa riferimento a un tipo di diritti che storicamente fecero la [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[1],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/8819"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=8819"}],"version-history":[{"count":11,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/8819\/revisions"}],"predecessor-version":[{"id":9841,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/8819\/revisions\/9841"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=8819"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=8819"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=8819"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}