{"id":89880,"date":"2016-07-15T00:04:04","date_gmt":"2016-07-14T22:04:04","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=89880"},"modified":"2016-07-14T09:27:30","modified_gmt":"2016-07-14T07:27:30","slug":"la-mia-cucina-fusion-gusto-giusto-equipe-propone-conchiglie-alla-vogherese-vegan","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2016\/07\/15\/la-mia-cucina-fusion-gusto-giusto-equipe-propone-conchiglie-alla-vogherese-vegan\/","title":{"rendered":"&#8220;La mia cucina fusion&#8221; \/ GUSTO GIUSTO EQUIPE PROPONE: &#8220;CONCHIGLIE ALLA VOGHERESE&#8221;, vegan"},"content":{"rendered":"<p><strong><img decoding=\"async\" loading=\"lazy\" width=\"640\" height=\"480\" title=\"co\" class=\"alignleft size-full wp-image-89886\" alt=\"\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2016\/07\/co1.jpg\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2016\/07\/co1.jpg 640w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2016\/07\/co1-300x225.jpg 300w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2016\/07\/co1-400x300.jpg 400w\" sizes=\"(max-width: 640px) 100vw, 640px\" \/>CONCHIGLIE ALLA VOGHERESE<\/strong> (per 4\/5 persone), RICETTA VEGANA______<\/p>\n<p>1 scatola da 500 g di conchiglie \u2013 \u00bd Kg di peperoni \u2013 \u00bd Kg di pomodori \u2013 1 cipolla \u2013 1 ciuffo di basilico \u2013 sale e pepe &#8211; olio e burro q.b._____<\/p>\n<p>lavate, asciugate, e tagliate a spicchi i peperoni; togliete i semi e i filamenti bianchi; pelate i pomodori, tagliateli a pezzetti e levate i semi; affettate sottilmente la cipolla.<\/p>\n<p>Fate soffriggere la cipolla in una padella con abbondante oli e un po&#8217; di burro; unite i peperoni, salate e lasciate cuocere, a fuoco piuttosto alto, mescolando spesso; quando i peperoni cominciano a diventare teneri, aggiungete i pomodori e il basilico; salate, pepate, abbassate la fiamma, coprite e lasciate finire di cuocere, all&#8217;ultimo togliete il coperchio e fate evaporare tutta l&#8217;acqua dei pomodori. Fate cuocere al dente le conchiglie e uniteli alla peperonata_____<\/p>\n<p>BUON APPETITO A TUTTI!<\/p>\n<p>GUSTO GIUSTO equipe<\/p>\n<p>Il vino consigliato \u00e8: LUGANA, TREBBIANO<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2016\/07\/15\/la-mia-cucina-fusion-gusto-giusto-equipe-propone-conchiglie-alla-vogherese-vegan\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2016\/07\/15\/la-mia-cucina-fusion-gusto-giusto-equipe-propone-conchiglie-alla-vogherese-vegan\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>CONCHIGLIE ALLA VOGHERESE (per 4\/5 persone), RICETTA VEGANA______ 1 scatola da 500 g di conchiglie \u2013 \u00bd Kg di peperoni \u2013 \u00bd Kg di pomodori \u2013 1 cipolla \u2013 1 ciuffo di basilico \u2013 sale e pepe &#8211; olio e burro q.b._____ lavate, asciugate, e tagliate a spicchi i peperoni; togliete i semi e i [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":89886,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[1],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/89880"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=89880"}],"version-history":[{"count":2,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/89880\/revisions"}],"predecessor-version":[{"id":90952,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/89880\/revisions\/90952"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/89886"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=89880"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=89880"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=89880"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}