{"id":89924,"date":"2016-07-05T00:05:52","date_gmt":"2016-07-04T22:05:52","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=89924"},"modified":"2016-07-04T13:49:12","modified_gmt":"2016-07-04T11:49:12","slug":"i-nostri-amici-animali-le-storie-di-federica-188","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2016\/07\/05\/i-nostri-amici-animali-le-storie-di-federica-188\/","title":{"rendered":"I NOSTRI AMICI ANIMALI \/ LE STORIE DI FEDERICA"},"content":{"rendered":"<p><img decoding=\"async\" loading=\"lazy\" width=\"720\" height=\"960\" title=\"13590228_1138268029583036_2269382268779143134_n\" class=\"aligncenter size-full wp-image-89925\" alt=\"\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2016\/07\/13590228_1138268029583036_2269382268779143134_n.jpg\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2016\/07\/13590228_1138268029583036_2269382268779143134_n.jpg 720w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2016\/07\/13590228_1138268029583036_2269382268779143134_n-225x300.jpg 225w\" sizes=\"(max-width: 720px) 100vw, 720px\" \/>Eppure, glielo aveva detto, il nostro amico Antonio Nuzzoli, glielo aveva spiegato in tutti i modi: -&#8220;fa caldo, non venire, perch\u00e9 devi seguimi a tutti i costi? vado da solo, a fare la mia ginnastica mattutina, oggi devo fare pi\u00f9 strada&#8230;&#8221;.<\/p>\n<p>Ma non c&#8217;\u00e8 stato niente da fare: accompagnamento, anzi, tallonamento, costante.<\/p>\n<p>Poi, tornati a casa, questi sono i risultati&#8230;<\/p>\n<p>&nbsp;<\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2016\/07\/05\/i-nostri-amici-animali-le-storie-di-federica-188\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2016\/07\/05\/i-nostri-amici-animali-le-storie-di-federica-188\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>Eppure, glielo aveva detto, il nostro amico Antonio Nuzzoli, glielo aveva spiegato in tutti i modi: -&#8220;fa caldo, non venire, perch\u00e9 devi seguimi a tutti i costi? vado da solo, a fare la mia ginnastica mattutina, oggi devo fare pi\u00f9 strada&#8230;&#8221;. Ma non c&#8217;\u00e8 stato niente da fare: accompagnamento, anzi, tallonamento, costante. Poi, tornati a [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":89925,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[78],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/89924"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=89924"}],"version-history":[{"count":2,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/89924\/revisions"}],"predecessor-version":[{"id":89927,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/89924\/revisions\/89927"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/89925"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=89924"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=89924"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=89924"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}