{"id":89948,"date":"2016-07-05T00:07:34","date_gmt":"2016-07-04T22:07:34","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=89948"},"modified":"2016-07-04T14:54:06","modified_gmt":"2016-07-04T12:54:06","slug":"diario-del-giorno-prima-il-tam-tam-di-annibale-119","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2016\/07\/05\/diario-del-giorno-prima-il-tam-tam-di-annibale-119\/","title":{"rendered":"DIARIO DEL GIORNO PRIMA \/ IL TAM TAM DI ANNIBALE"},"content":{"rendered":"<p><img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2016\/07\/3_milano-esplosione-fotogramma-300x187.jpg\" alt=\"\" title=\"3_milano-esplosione-fotogramma\" width=\"300\" height=\"187\" class=\"alignleft size-medium wp-image-89949\" \/>ITALIA______<br \/>\nMILANO &#8211; Giuseppe Pellican\u00f2 ha confessato di aver svitato il tubo del gas nel suo appartamento in via Brioschi a Milano, provocando l&#8217;esplosione della palazzina nella quale 12 giugno sono morti l&#8217;ex compagna Micaela ei giovani fidanzati Marchegiani Chiara Magnamassa e Riccardo Maglianesi. \u00c8 quanto emerge dal provvedimento con cui il gip di Milano ha disposto la custodia cautelare in carcere per il pubblicitario fermato per strage venerd\u00ec.<\/p>\n<p>ITALIA______<br \/>\nBERGAMO &#8211; Un trentasettenne un trentacinquenne di Bergamo sono morti mentre scalavano la parete nord del monte Disgrazia in Valtellina, un nome che \u00e8 tutto un programma. I due erano saliti in vetta in cordata lungo la via normale, ma un certo punto uno dei due ha perso l&#8217;equilibrio ed \u00e8 caduto trascinando con se anche l&#8217;altro. L&#8217;allarme \u00e8 scattato intorno alle 9:30, quando i soccorritori sono giunti sul posto per i due alpinisti non c&#8217;\u00e8 pi\u00f9 nulla da fare.<\/p>\n<p>MONDO______<br \/>\nLONDRA &#8211; Dopo le polemiche e contropolemiche sulla querelle Brexit, la questione \u00e8 finita in mano agli avvocati del prestigioso studio legale londinese\u00a0 &#8220;Nischon de Reya&#8221; ha infatti chiesto garanzie che il procedimento formale per l&#8217;uscita della Gran Bretagna dall&#8217;Unione Europea non inizi prima del tempo previsto. Si richiede un atto ufficiale del Parlamento, poich\u00e9 il referendum \u00e8 puramente consultivo e lo studio legale \u00e8 pronto a far ricorso alle aule di giustizia nel caso le garanzie richieste non vengono fornite in tempo. La questione Brexit \u00e8 tutt&#8217;altro che chiusa.<\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2016\/07\/05\/diario-del-giorno-prima-il-tam-tam-di-annibale-119\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2016\/07\/05\/diario-del-giorno-prima-il-tam-tam-di-annibale-119\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>ITALIA______ MILANO &#8211; Giuseppe Pellican\u00f2 ha confessato di aver svitato il tubo del gas nel suo appartamento in via Brioschi a Milano, provocando l&#8217;esplosione della palazzina nella quale 12 giugno sono morti l&#8217;ex compagna Micaela ei giovani fidanzati Marchegiani Chiara Magnamassa e Riccardo Maglianesi. \u00c8 quanto emerge dal provvedimento con cui il gip di Milano [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":89949,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[1,69,76],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/89948"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=89948"}],"version-history":[{"count":1,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/89948\/revisions"}],"predecessor-version":[{"id":89950,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/89948\/revisions\/89950"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/89949"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=89948"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=89948"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=89948"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}