{"id":89968,"date":"2016-07-05T00:10:32","date_gmt":"2016-07-04T22:10:32","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=89968"},"modified":"2016-07-05T10:47:20","modified_gmt":"2016-07-05T08:47:20","slug":"diario-di-euro-2016-conte-il-mio-non-e-un-addio-ma-un-arrivederci-ora-tocca-a-ventura","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2016\/07\/05\/diario-di-euro-2016-conte-il-mio-non-e-un-addio-ma-un-arrivederci-ora-tocca-a-ventura\/","title":{"rendered":"DIARIO DI EURO 2016 \/ CONTE: IL MIO NON E&#8217; UN ADDIO, MA UN ARRIVEDERCI. ORA TOCCA A VENTURA"},"content":{"rendered":"<p>di <strong>Francesco<\/strong> <strong>Giannetta<\/strong> ______<\/p>\n<p>Terminata non senza rammarico l&#8217;avventura di Euro 2016, gli azzurri hanno fatto rientro in patria. A Malpensa hanno trovato ad attenderli una folla di circa trecento persone che con cori, bandiere e striscioni hanno fatto commuovere i nazionali italiani, ma ad apparire pi\u00f9 emozionato di tutti \u00e8 stato senza dubbio Antonio Conte. L&#8217;ormai ex c.t. azzurro ha ricevuto un accoglienza degna di un divo di Hollywood e ha fatto non poca fatica a trattenere le lacrime. Conte ha precisato che il suo non \u00e8 un addio alla Nazionale Italiana ma un arrivederci, dello stesso parere \u00e8 Tavecchio: &#8220;E&#8217; giovane, chissa&#8217; un giorno&#8230;&#8221;<\/p>\n<p><img decoding=\"async\" loading=\"lazy\" width=\"728\" height=\"410\" title=\"180800481-86faa71d-022b-4c76-b31e-912446cd4084\" class=\"aligncenter size-full wp-image-89980\" alt=\"\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2016\/07\/180800481-86faa71d-022b-4c76-b31e-912446cd4084.jpg\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2016\/07\/180800481-86faa71d-022b-4c76-b31e-912446cd4084.jpg 728w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2016\/07\/180800481-86faa71d-022b-4c76-b31e-912446cd4084-300x169.jpg 300w\" sizes=\"(max-width: 728px) 100vw, 728px\" \/><\/p>\n<p>Ora per\u00f2 \u00e8 il momento di ringraziare Conte per il sogno che ci ha fatto vivere e per l&#8217;impresa che ci ha fatto assaporare e di guardare avanti e dare tutta la nostra fiducia a Giampiero Ventura, prossimo c.t. azzurro. Il mister ex toro ripartir\u00e0 dal 3-5-2 di matrice contiana e dal blocco difensivo targato Juve che rischia per\u00f2 di perdere Barzagli, il quale aveva manifestato la volont\u00e0 di dire addio alla nazionale. Probabilmente Ventura porter\u00e0 nel giro della nazionale i suoi uomini come Benassi, Zappacosta e Belotti, gi\u00e0 in passato vicini alla convocazione. In attacco in particolare si vocifera sul possibile tandem Belotti &#8211; Berardi, per ringiovanire una nazionale che sente il peso degli anni. A centrocampo si punta sul recupero di Marchisio e Verratti, giocatori fondamentali per le idee di gioco del nuovo mister. La prima missione di Ventura non \u00e8 affatto semplice perch\u00e9 non sar\u00e0 una passeggiata strappare il pass per i mondiali in Russia nel 2018. Nel nostro girone di qualificazione ci attendono squadre agguerrite e motivate come Israele, Albania e la &#8220;nuova&#8221; Spagna. Il primo impegno della nazionale di Ventura sar\u00e0 ad inizio settembre contro la Francia, in amichevole a Bari, citt\u00e0 cara al nuovo c.t. azzurro.<\/p>\n<p><img decoding=\"async\" loading=\"lazy\" width=\"638\" height=\"382\" title=\"giampiero-ventura_h_partb\" class=\"aligncenter size-full wp-image-89981\" alt=\"\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2016\/07\/giampiero-ventura_h_partb.jpg\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2016\/07\/giampiero-ventura_h_partb.jpg 638w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2016\/07\/giampiero-ventura_h_partb-300x180.jpg 300w\" sizes=\"(max-width: 638px) 100vw, 638px\" \/><\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2016\/07\/05\/diario-di-euro-2016-conte-il-mio-non-e-un-addio-ma-un-arrivederci-ora-tocca-a-ventura\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2016\/07\/05\/diario-di-euro-2016-conte-il-mio-non-e-un-addio-ma-un-arrivederci-ora-tocca-a-ventura\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>di Francesco Giannetta ______ Terminata non senza rammarico l&#8217;avventura di Euro 2016, gli azzurri hanno fatto rientro in patria. A Malpensa hanno trovato ad attenderli una folla di circa trecento persone che con cori, bandiere e striscioni hanno fatto commuovere i nazionali italiani, ma ad apparire pi\u00f9 emozionato di tutti \u00e8 stato senza dubbio Antonio [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":89980,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[1,75,28],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/89968"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=89968"}],"version-history":[{"count":5,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/89968\/revisions"}],"predecessor-version":[{"id":89987,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/89968\/revisions\/89987"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/89980"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=89968"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=89968"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=89968"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}