{"id":90063,"date":"2016-07-07T00:06:44","date_gmt":"2016-07-06T22:06:44","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=90063"},"modified":"2016-07-06T12:17:35","modified_gmt":"2016-07-06T10:17:35","slug":"grazie-per-la-foto-207","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2016\/07\/07\/grazie-per-la-foto-207\/","title":{"rendered":"GRAZIE PER LA FOTO"},"content":{"rendered":"<p>Grazie per la foto alla pagina Facebook di &#8220;La Notte della Taranta&#8221;, che s\u00ec raffigura in questo scatto meraviglioso e mirabolante lo spettacolo di Santa Domenica, a Scorrano, nel profondo del Salento.<\/p>\n<p>La bellezza di questa villa \u00e8 issata al centro della localit\u00e0 per le celebrazioni della santa patrona \u00e8 una delle attrazioni principali di una terra fortemente legata alle proprie tradizioni o focoso&#8230;<\/p>\n<p>&nbsp;<\/p>\n<p><img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2016\/07\/FB_IMG_1467792408686.jpg\" alt=\"\" title=\"FB_IMG_1467792408686\" width=\"528\" height=\"686\" class=\"aligncenter size-full wp-image-90064\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2016\/07\/FB_IMG_1467792408686.jpg 528w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2016\/07\/FB_IMG_1467792408686-231x300.jpg 231w\" sizes=\"(max-width: 528px) 100vw, 528px\" \/><\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2016\/07\/07\/grazie-per-la-foto-207\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2016\/07\/07\/grazie-per-la-foto-207\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>Grazie per la foto alla pagina Facebook di &#8220;La Notte della Taranta&#8221;, che s\u00ec raffigura in questo scatto meraviglioso e mirabolante lo spettacolo di Santa Domenica, a Scorrano, nel profondo del Salento. La bellezza di questa villa \u00e8 issata al centro della localit\u00e0 per le celebrazioni della santa patrona \u00e8 una delle attrazioni principali di [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":90064,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[1,31],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/90063"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=90063"}],"version-history":[{"count":2,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/90063\/revisions"}],"predecessor-version":[{"id":90066,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/90063\/revisions\/90066"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/90064"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=90063"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=90063"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=90063"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}