{"id":90075,"date":"2016-07-19T00:04:14","date_gmt":"2016-07-18T22:04:14","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=90075"},"modified":"2016-07-06T13:27:54","modified_gmt":"2016-07-06T11:27:54","slug":"la-mia-cucina-fusion-gusto-giusto-equipe-con-la-dottoressa-chiaretta-edo-ergo-sum","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2016\/07\/19\/la-mia-cucina-fusion-gusto-giusto-equipe-con-la-dottoressa-chiaretta-edo-ergo-sum\/","title":{"rendered":"&#8220;La mia cucina fusion\u201d \/ GUSTO GIUSTO equipe, CON LA DOTTORESSA CHIARETTA: &#8220;Edo ergo sum&#8221;"},"content":{"rendered":"<p><img decoding=\"async\" loading=\"lazy\" width=\"1024\" height=\"576\" title=\"cibo-sano-1024x576\" class=\"alignleft size-full wp-image-90078\" alt=\"\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2016\/07\/cibo-sano-1024x576.jpg\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2016\/07\/cibo-sano-1024x576.jpg 1024w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2016\/07\/cibo-sano-1024x576-300x169.jpg 300w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2016\/07\/cibo-sano-1024x576-768x432.jpg 768w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>Si parla ogni giorno di cucina, alimentazione e nutrizione, secondo i propri convincimenti, principi, filosofie personali. Una cosa \u00e8 certa. Nulla viene scelto con cognizione di causa. E&#8217; un rincorrere di mode, pregiudizi, pubblicit\u00e0, passa-parola. Tutti dicono, raccontano, hanno pretesa d&#8217;insegnare, una materia cos\u00ec complessa, come l&#8217;alimentazione equilibrata. Sembriamo, come i tifosi di calcio quando \u00e8 ora di fare la formazione della nazionale. Siamo tutti competenti, tutti esperti allenatori, fino al momento in cui sbagliamo clamorosamente e rimbrottiamo dicendo -:\u201dEheheeee, io l&#8217;avevo detto, io!\u2026&#8230; (esattamente in contrario!)\u201d.<\/p>\n<p>Teniamo a precisare: ogni piatto, ogni ricetta, che esce da Gusto Giusto, viene esaminato dalla nostra dottoressa Chiaretta, con la quale studio, da anni: il buon vivere, il buon cibo, la buona salute e la felicit\u00e0 del palato.<\/p>\n<p>Non siamo integraliste, perch\u00e9 ci sembrerebbe di vestire sempre di rosso o di blu o altro, quando il mondo e variopinto!\u2026. Ma ve lo faccio dire da Lei:<\/p>\n<p>EDO, ERGO SUM:<\/p>\n<p>della Dott.ssa CHIARETTA della nostra equipe______<\/p>\n<p>L&#8217;alimentazione condiziona in modo determinante le vita dell&#8217;uomo.<\/p>\n<p>Alimentarsi significa crescere, fare proprio l&#8217;ambiente nella sua totalit\u00e0, assorbire attraverso il cibo vivo l&#8217;ENERGIA del pianeta: ARIA, ACQUA, TERRA e LUCE SOLARE.<\/p>\n<p>Mangiamo, prima di tutto, Energia vitale e ci\u00f2 \u00e8 atto sacro, nella forma e nell&#8217;essenza.<\/p>\n<p>Riconosciamo la potenzialit\u00e0 negli alimenti che hanno capacit\u00e0 riproduttiva, quella che consente ad un chicco di grano integrale, per esempio, di riprendere il ciclo di germogliazione, una volta messo nella nuda terra madre.<\/p>\n<p>Nella frutta e nella verdura appena colta, \u00e8 ancora presente la forza connessa al proprio scopo vitale.<\/p>\n<p>Secondi il metodo della conservazione dei cibi, l&#8217;essiccazione \u00e8 l&#8217;unico che mantiene l&#8217;Energia.<\/p>\n<p>La cottura, in linea di principio, cambia notevolmente la qualit\u00e0 organolettica degli alimenti, ed \u00e8 preferibile quella al vapore o al forno. Questo, per esempio, non vale nella cultura Veda, che invece predilige la lunga cottura, in quanto ritiene che possa facilitare ed accelerare il processo complessivo di evoluzione, cui il corpo \u00e8 costantemente sottoposto.<\/p>\n<p>Cotto \u00e8, principalmente, ci\u00f2 che \u00e8 stato maturato al sole, Primo e Supremo Agente.<\/p>\n<p>Annusiamo, guardiamo, assaggiamo, la freschezza non dovrebbe essere un&#8217; opinione.<\/p>\n<p>La SALUTE, \u00e8 il risultato di processi complessi che, prima di tutto, si realizzano nella mente dell&#8217;uomo, attraverso una presa di coscienza e valutazione.<\/p>\n<p>Affidarci a noi stessi (istinto), \u00e8 una pratica ormai dimenticata, ma \u00e8 tutto ci\u00f2 che occorre.<\/p>\n<p>E&#8217; nell&#8217;ascolto individuale dell&#8217;intelligenza pura del corpo, che si verifica la cura.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2016\/07\/19\/la-mia-cucina-fusion-gusto-giusto-equipe-con-la-dottoressa-chiaretta-edo-ergo-sum\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2016\/07\/19\/la-mia-cucina-fusion-gusto-giusto-equipe-con-la-dottoressa-chiaretta-edo-ergo-sum\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>Si parla ogni giorno di cucina, alimentazione e nutrizione, secondo i propri convincimenti, principi, filosofie personali. Una cosa \u00e8 certa. Nulla viene scelto con cognizione di causa. E&#8217; un rincorrere di mode, pregiudizi, pubblicit\u00e0, passa-parola. Tutti dicono, raccontano, hanno pretesa d&#8217;insegnare, una materia cos\u00ec complessa, come l&#8217;alimentazione equilibrata. Sembriamo, come i tifosi di calcio quando [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":90078,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[1],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/90075"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=90075"}],"version-history":[{"count":2,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/90075\/revisions"}],"predecessor-version":[{"id":90080,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/90075\/revisions\/90080"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/90078"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=90075"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=90075"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=90075"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}