{"id":90216,"date":"2016-07-07T17:34:12","date_gmt":"2016-07-07T15:34:12","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=90216"},"modified":"2016-07-07T17:36:05","modified_gmt":"2016-07-07T15:36:05","slug":"opereremo-nel-territorio-salentino-per-i-prossimi-cinquanta-anni-la-promessa-minaccia-accompagnata-dall-incredibile-riassicurazione-di-voler-dare-il-proprio-contributo-alla-crescita-e-in","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2016\/07\/07\/opereremo-nel-territorio-salentino-per-i-prossimi-cinquanta-anni-la-promessa-minaccia-accompagnata-dall-incredibile-riassicurazione-di-voler-dare-il-proprio-contributo-alla-crescita-e-in\/","title":{"rendered":"&#8220;Opereremo nel territorio salentino per i prossimi cinquanta anni&#8221;. LA PROMESSA \/ MINACCIA ACCOMPAGNATA DALL&#8217; INCREDIBILE RIASSICURAZIONE DI VOLER DARE &#8220;il proprio contributo alla crescita&#8221;. E INTANTO LA TAP RIPRENDE A DARE SOLDI IN GIRO, 25 000 EURO A BOTTA, PER CERCARE DI COMPRARE IL CONSENSO"},"content":{"rendered":"<p><img decoding=\"async\" loading=\"lazy\" width=\"700\" height=\"466\" title=\"Mario-Michele-Elia-Trenitalia\" class=\"aligncenter size-full wp-image-90217\" alt=\"\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2016\/07\/Mario-Michele-Elia-Trenitalia.jpg\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2016\/07\/Mario-Michele-Elia-Trenitalia.jpg 700w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2016\/07\/Mario-Michele-Elia-Trenitalia-300x200.jpg 300w\" sizes=\"(max-width: 700px) 100vw, 700px\" \/>(Rdl)______Un comunicato appena arrivato in redazione, annuncia &#8220;<em>200mila euro a sostegno di progetti di associazioni ed enti no profit: primo investimento per il miglioramento della qualit\u00e0 della vita mediante il sostegno di iniziative finalizzate alla realizzazione di progetti sociali culturali e ambientali a Melendugno&#8221;.<\/em><\/p>\n<p>Viene\u00a0specificato che <em>&#8220;saranno ammessi al finanziamento per non pi\u00f9 di 25mila euro progetti presentati tra il 15 luglio prossimo e il 30 settembre da associazioni ed enti senza fini di lucro con sede legale nel Comune di Melendugno e che rispondano ai quattro obiettivi generali del Programma di Investimento Socio-Ambientale di TAP Sviluppo economico locale, Qualit\u00e0 della vita, Sviluppo delle competenze, Tutela dell\u2019ambiente. Ammissibili anche progetti presentati in partenariato con associazioni ed enti no profit italiani o con entit\u00e0 pubbliche (Enti locali, scuole, strutture sociosanitarie, ecc.).<\/em><\/p>\n<p><em>I progetti saranno valutati da una apposita commissione formata da esperti indipendenti che stileranno l\u2019elenco dei vincitori che sar\u00e0 poi annunciato entro la fine dell\u2019anno; i progetti dovranno essere realizzati nel corso del 2017. Il bando potr\u00e0 essere replicato due volte l\u2019anno durante il periodo della costruzione del gasdotto, per un totale di 1 milione 400mila euro a sostegno di progetti&#8221;.<\/em><\/p>\n<p>Secondo quanto scritto dal massimo dirigente Michele Elia (nella foto),\u00a0<em>\u00abTAP intende agire come un componente non occasionale del panorama economico e sociale di Melendugno e del Salento, e dare, come spetta ad ogni cittadino, impresa o associazione, il proprio contributo alla crescita di un territorio nel quale operer\u00e0 come minimo per i prossimi cinquant\u2019anni. Altri interventi seguiranno, e l\u2019augurio di TAP \u00e8 che questo avvenga con il progressivo coinvolgimento delle istituzioni locali\u00bb.<\/em><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2016\/07\/07\/opereremo-nel-territorio-salentino-per-i-prossimi-cinquanta-anni-la-promessa-minaccia-accompagnata-dall-incredibile-riassicurazione-di-voler-dare-il-proprio-contributo-alla-crescita-e-in\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2016\/07\/07\/opereremo-nel-territorio-salentino-per-i-prossimi-cinquanta-anni-la-promessa-minaccia-accompagnata-dall-incredibile-riassicurazione-di-voler-dare-il-proprio-contributo-alla-crescita-e-in\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>(Rdl)______Un comunicato appena arrivato in redazione, annuncia &#8220;200mila euro a sostegno di progetti di associazioni ed enti no profit: primo investimento per il miglioramento della qualit\u00e0 della vita mediante il sostegno di iniziative finalizzate alla realizzazione di progetti sociali culturali e ambientali a Melendugno&#8221;. Viene\u00a0specificato che &#8220;saranno ammessi al finanziamento per non pi\u00f9 di 25mila [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":90217,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[69],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/90216"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=90216"}],"version-history":[{"count":3,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/90216\/revisions"}],"predecessor-version":[{"id":90219,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/90216\/revisions\/90219"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/90217"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=90216"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=90216"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=90216"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}