{"id":90359,"date":"2016-07-08T18:44:09","date_gmt":"2016-07-08T16:44:09","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=90359"},"modified":"2016-07-11T13:07:17","modified_gmt":"2016-07-11T11:07:17","slug":"le-idee-un-altra-europa-e-possibile-parola-di-jeremy-rifkin","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2016\/07\/08\/le-idee-un-altra-europa-e-possibile-parola-di-jeremy-rifkin\/","title":{"rendered":"LE IDEE \/ UN&#8217; ALTRA EUROPA E&#8217; POSSIBILE. PAROLA DI JEREMY RIFKIN"},"content":{"rendered":"<p><img decoding=\"async\" loading=\"lazy\" width=\"1024\" height=\"682\" title=\"JeremyRifkin\" class=\"alignleft size-large wp-image-90363\" alt=\"\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2016\/07\/JeremyRifkin-1024x682.jpg\" \/>(g..p.)______Jeremy Rifkin, il teorico della terza rivoluzione industriale, oggi da Bratislava ha proposto la sua &#8216;cura&#8217; per guarire le malattie dell&#8217; Unione Europea.<\/p>\n<p>&#8220;<em>Basta con l&#8217;Europa ossessionata dal debito. La Brexit ha dimostrato che questa Europa ha fallito, ma c&#8217;\u00e8 un&#8217;altra Europa che punta al rilancio partendo dal basso, che scommette su un&#8217;economia sociale e collaborativa, che \u00e8 in grado di migliorare la qualit\u00e0 della vita di tutti.\u00a0Occorre passare dal neoliberismo imperante a parametri qualitativi: miglioramento della scolarizzazione, sanit\u00e0 pi\u00f9 efficiente, difesa dell&#8217;ambiente. Un social compact al posto del fiscal compact&#8230;Stiamo rubando l&#8217;equilibrio del pianeta, le condizioni necessarie a garantire la sopravvivenza. <\/em><\/p>\n<p><em>Inoltre in Europa le spese per le infrastrutture della seconda rivoluzione industriale, quella che sta tramontando, ammontano a circa 750 miliardi di euro l&#8217;anno. Basterebbe riconvertirne una parte per avere una forte spinta innovativa a costo zero.\u00a0<\/em><\/p>\n<p><em>&#8220;Bisogna spingere in direzione dell&#8217;internet della comunicazione, dell&#8217;internet delle energie rinnovabili e dell&#8217;internet della nuova mobilit\u00e0. Scommettere sul digitale vuol dire realizzare formidabili risparmi migliorando sensibilmente i servizi&#8230;<\/em><\/p>\n<p><em>E&#8217; necessario\u00a0\u00a0abbattere i consumi energetici e gli sprechi migliorando la qualit\u00e0 dell&#8217;ambiente e il livello di vita dei cittadini. <\/em><\/p>\n<p><em>E&#8217; l&#8217;unica strada da percorrere perch\u00e9 la vecchia economia ha fallito: le crisi che stiamo attraversando, da quella economica a quella sociale, lo dimostrano&#8221;.<\/em><\/p>\n<p><strong>LA DOCUMENTAZIONE<\/strong>______<\/p>\n<p>Jeremy Rifkin, economista, attivista e saggista statunitense, ha 71 anni.<\/p>\n<p>Attivista del movimento pacifista e ambientalista statunitense negli anni Sessanta e Settanta; impegnato a sostegno dell&#8217;adozione di politiche governative &#8220;responsabili&#8221; in diversi ambiti, sia relativi all&#8217;ambiente, sia alla\u00a0tecnologia;\u00a0impegno teorizzato\u00a0in numerosi dei suoi saggi e lavori. \u00c8 vegetariano.<\/p>\n<p>Con il suo trattato del 1977 &#8220;Who Should Play God?&#8221; \u00e8 stato uno dei primi a criticare l&#8217;allora nascente scienza delle biotecnologie.<\/p>\n<p>Nel 1992 lancia il suo J&#8217;accuse contro quella che chiama la &#8220;cultura della bistecca&#8221; con il saggio &#8220;Ecocidio&#8221;.<\/p>\n<p>Nel 1995 scrive &#8220;La fine del lavoro&#8221;: il declino della forza lavoro globale e l&#8217;avvento dell&#8217;era post-mercato, in cui prefigura\u00a0il definitivo trionfo delle macchine sul lavoro umano, proponendo possibili soluzioni per ridurre l&#8217;impatto sociale e anzi trarre vantaggio da questa trasformazione.<\/p>\n<p>Nel 2010 esce in Italia il libro &#8220;La civilt\u00e0 dell&#8217;empatia2, cui segue &#8220;La civilt\u00e0 dell&#8217; idrogeno&#8221;.<\/p>\n<p>Nel 2013 partecipa al V-Day 3 organizzato da Beppe Grillo e, tramite un videomessaggio, spiega in maniera dettagliata la fine dell&#8217;et\u00e0 industriale, la necessit\u00e0 di cambiare le nostre fonti energetiche, passando gradualmente dall&#8217;estrazione dei combustili fossili alle fonti rinnovabili, il cambiamento climatico e la variazione sconvolgente del ciclo dell&#8217;acqua sulla Terra.<\/p>\n<p>In aggiunta al suo impegno negli Stati Uniti, Rifkin \u00e8 stato attivo anche in Europa come consigliere di alcuni capi di governo e, in particolare, ha operato come consigliere personale sulle questioni energetiche di Romano Prodi.<\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2016\/07\/08\/le-idee-un-altra-europa-e-possibile-parola-di-jeremy-rifkin\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2016\/07\/08\/le-idee-un-altra-europa-e-possibile-parola-di-jeremy-rifkin\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>(g..p.)______Jeremy Rifkin, il teorico della terza rivoluzione industriale, oggi da Bratislava ha proposto la sua &#8216;cura&#8217; per guarire le malattie dell&#8217; Unione Europea. &#8220;Basta con l&#8217;Europa ossessionata dal debito. La Brexit ha dimostrato che questa Europa ha fallito, ma c&#8217;\u00e8 un&#8217;altra Europa che punta al rilancio partendo dal basso, che scommette su un&#8217;economia sociale e [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":90363,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[69,31,76],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/90359"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=90359"}],"version-history":[{"count":2,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/90359\/revisions"}],"predecessor-version":[{"id":90579,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/90359\/revisions\/90579"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/90363"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=90359"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=90359"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=90359"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}