{"id":90497,"date":"2016-07-10T12:05:04","date_gmt":"2016-07-10T10:05:04","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=90497"},"modified":"2016-07-10T12:05:04","modified_gmt":"2016-07-10T10:05:04","slug":"coltivazione-casalinga-di-marijuana-a-corsano","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2016\/07\/10\/coltivazione-casalinga-di-marijuana-a-corsano\/","title":{"rendered":"COLTIVAZIONE CASALINGA DI MARIJUANA A CORSANO"},"content":{"rendered":"<p><img decoding=\"async\" loading=\"lazy\" width=\"245\" height=\"300\" title=\"O\" class=\"alignright size-medium wp-image-90502\" alt=\"\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2016\/07\/O-245x300.png\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2016\/07\/O-245x300.png 245w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2016\/07\/O.png 308w\" sizes=\"(max-width: 245px) 100vw, 245px\" \/>(g.m.)_____Nel corso di una perquisizione domiciliare in casa sua, i carabinieri, che lo tenevano da giorni sotto controllo,\u00a0hanno trovato (nelle foto):\u00a0sei vasi con altrettante piante di marijuana alte circa un metro mezzo;\u00a0mezzo panetto di hashish dal peso di circa\u00a0sessanta grammi e altri\u00a0venti grammi di marijuana mista ad hashish;\u00a0materiale per la coltivazione; una serra ben ventilata per l\u2019essicazione; un bilancino elettronico;\u00a0210 euro in banconote di piccolo taglio.<\/p>\n<p>Per questo motivo\u00a0Salvatore Boccarello (nella foto), 48 anni, originario di Gallipoli, residente a Corsano, \u00e8 stato arrestato e posto ai domiciliari.<\/p>\n<p><img decoding=\"async\" loading=\"lazy\" width=\"225\" height=\"300\" title=\"image1\" class=\"alignright size-medium wp-image-90503\" alt=\"\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2016\/07\/image1-225x300.jpg\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2016\/07\/image1-225x300.jpg 225w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2016\/07\/image1-768x1024.jpg 768w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2016\/07\/image1-1152x1536.jpg 1152w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2016\/07\/image1.jpg 1200w\" sizes=\"(max-width: 225px) 100vw, 225px\" \/><img decoding=\"async\" loading=\"lazy\" width=\"300\" height=\"225\" title=\"image2\" class=\"alignright size-medium wp-image-90505\" alt=\"\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2016\/07\/image2-300x225.jpg\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2016\/07\/image2-300x225.jpg 300w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2016\/07\/image2-1024x768.jpg 1024w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2016\/07\/image2-768x576.jpg 768w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2016\/07\/image2-1536x1152.jpg 1536w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2016\/07\/image2-400x300.jpg 400w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2016\/07\/image2.jpg 1600w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2016\/07\/10\/coltivazione-casalinga-di-marijuana-a-corsano\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2016\/07\/10\/coltivazione-casalinga-di-marijuana-a-corsano\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>(g.m.)_____Nel corso di una perquisizione domiciliare in casa sua, i carabinieri, che lo tenevano da giorni sotto controllo,\u00a0hanno trovato (nelle foto):\u00a0sei vasi con altrettante piante di marijuana alte circa un metro mezzo;\u00a0mezzo panetto di hashish dal peso di circa\u00a0sessanta grammi e altri\u00a0venti grammi di marijuana mista ad hashish;\u00a0materiale per la coltivazione; una serra ben ventilata [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":90502,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[69],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/90497"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=90497"}],"version-history":[{"count":1,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/90497\/revisions"}],"predecessor-version":[{"id":90506,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/90497\/revisions\/90506"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/90502"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=90497"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=90497"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=90497"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}