{"id":90557,"date":"2016-07-11T11:47:24","date_gmt":"2016-07-11T09:47:24","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=90557"},"modified":"2016-07-11T14:55:11","modified_gmt":"2016-07-11T12:55:11","slug":"gallipoli-sequestrata-discoteca-abusiva","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2016\/07\/11\/gallipoli-sequestrata-discoteca-abusiva\/","title":{"rendered":"&#8220;Italiani Mambo&#8230;&#8221; MA ARRIVA LA FINANZA E CHIUDE LA DISCOTECA DI SANNICOLA. DENUNCIATO IL GIOVANE GESTORE: NON AVEVA RISPETTATO LE PRESCRIZIONI"},"content":{"rendered":"<p style=\"text-align: left;\" align=\"center\"><img decoding=\"async\" loading=\"lazy\" width=\"960\" height=\"720\" title=\"13567251_10154316719477533_2433061156692953629_n\" class=\"alignleft size-full wp-image-90598\" alt=\"\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2016\/07\/13567251_10154316719477533_2433061156692953629_n.jpg\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2016\/07\/13567251_10154316719477533_2433061156692953629_n.jpg 960w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2016\/07\/13567251_10154316719477533_2433061156692953629_n-300x225.jpg 300w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2016\/07\/13567251_10154316719477533_2433061156692953629_n-768x576.jpg 768w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2016\/07\/13567251_10154316719477533_2433061156692953629_n-400x300.jpg 400w\" sizes=\"(max-width: 960px) 100vw, 960px\" \/>(g.m.)_______Gallipoli continua ad essere &#8220;attenzionata&#8221; dalle forze dell&#8217;ordine. \u00a0Gli agenti della Guardia di Finanza\u00a0nello scorso fine settimana hanno sottoposto a sequestro preventivo un locale di pubblico intrattenimento e ritrovo (nella foto), il &#8216;Mambo italiano&#8217;,\u00a0sito sulla strada provinciale Gallipoli \u2013 Santa Maria al Bagno, nel territorio del comune di Sannicola, ed hanno denunciato il gestore, un giovane ventenne, in quanto privo delle necessarie autorizzazioni.<\/p>\n<p>Le verifiche dei militari hanno l\u2019importante scopo di garantire che il locale sia dotato delle indispensabili misure di sicurezza a tutela dell\u2019incolumit\u00e0 pubblica (uscite di sicurezza a norma, adeguato impianto antincendio, impianto elettrico conforme alle norme vigenti nonch\u00e9 barriere per limitare l\u2019impatto acustico).<\/p>\n<p>La discoteca posta in sequestro dalle Fiamme Gialle, ampia circa 3.400 mq. esercitava l\u2019attivit\u00e0 di intrattenimento musicale e danzante, pur possedendo esclusivamente la sola SCIA, segnalazione certificata di inizio attivit\u00e0 per la somministrazione di alimenti e bevande.<\/p>\n<p>Al momento del controllo:<\/p>\n<p>&#8211;\u00a0 nella discoteca erano presenti circa\u00a0seicento giovani avventori che si accalcavano sulle piste da ballo,<\/p>\n<p>&#8211;\u00a0 all\u2019esterno della stessa vi era un numero notevole di autovetture parcheggiate dai clienti fino ad un chilometro di distanza, giunti sul posto da ogni parte della Puglia, anche considerando l\u2019ampio flusso turistico che interessa il Salento nel periodo estivo. L\u2019evidente intasamento delle vie d\u2019accesso e di sgombero del locale avrebbe reso oltremodo difficoltoso, se non impossibile, l\u2019eventuale intervento di mezzi di soccorso in caso di pericolo.<\/p>\n<p>Al termine dell\u2019attivit\u00e0 di servizio, <strong>\u00e8 stato denunciato alla Procura della Repubblica presso il Tribunale di Lecce un ventenne del posto<\/strong> per il reato di apertura abusiva di luoghi di pubblico spettacolo, trattenimento e ritrovo senza aver rispettato le prescrizioni dell\u2019Autorit\u00e0 a tutela dell\u2019incolumit\u00e0 pubblica, previste dal Testo Unico sulle Leggi di Pubblica Sicurezza.<\/p>\n<p>Inoltre, <strong>sono stati identificati\u00a0undici lavoratori<\/strong>, tra cui baristi, parcheggiatori e camerieri, la cui posizione sar\u00e0 accertata sotto il profilo contributivo, assistenziale e previdenziale in materia di lavoro.<\/p>\n<p>Ora, riferito sui fatti, ci sia permesso aggiungere\u00a0alcune domande: ma se gli uffici rilasciassero in tempo reale le autorizzazioni, i nostri giovani sarebbero costretti a lavorare abusivamente? Quanta gente rimarr\u00e0 senza lavoro ora che questo locale chiude? Gli uffici tecnici hanno svolto \u00a0diligentemente il suo compito rispettando i tempi che la legge prescrive per rilasciare le autorizzazioni?<br \/>\nNon basta pi\u00f9 dire che gli imprenditori devono rispettare le leggi, le leggi dovrebbero essere rispettate prima di tutto da chi svolge una funzione pubblica, come i nostri burocrati, che spesso\u00a0bloccano le autorizzazioni.<\/p>\n<p>Al di l\u00e0 di questo caso, ma in generale, vorremmo che i\u00a0finanzieri, facessero quello che\u00a0ha consigliato il Presidente dell&#8217;Associazione Magistrati Piercamillo Davigo: si fingano imprenditori e presentino domande e progetti presso i diversi uffici, e poi annotino tutto. Se ne vedrebbero delle belle.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2016\/07\/11\/gallipoli-sequestrata-discoteca-abusiva\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2016\/07\/11\/gallipoli-sequestrata-discoteca-abusiva\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>(g.m.)_______Gallipoli continua ad essere &#8220;attenzionata&#8221; dalle forze dell&#8217;ordine. \u00a0Gli agenti della Guardia di Finanza\u00a0nello scorso fine settimana hanno sottoposto a sequestro preventivo un locale di pubblico intrattenimento e ritrovo (nella foto), il &#8216;Mambo italiano&#8217;,\u00a0sito sulla strada provinciale Gallipoli \u2013 Santa Maria al Bagno, nel territorio del comune di Sannicola, ed hanno denunciato il gestore, un [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":90598,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[69],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/90557"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=90557"}],"version-history":[{"count":7,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/90557\/revisions"}],"predecessor-version":[{"id":90562,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/90557\/revisions\/90562"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/90598"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=90557"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=90557"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=90557"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}