{"id":91503,"date":"2016-07-20T00:06:09","date_gmt":"2016-07-19T22:06:09","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=91503"},"modified":"2016-07-19T15:19:26","modified_gmt":"2016-07-19T13:19:26","slug":"grazie-per-la-foto-219","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2016\/07\/20\/grazie-per-la-foto-219\/","title":{"rendered":"GRAZIE PER LA FOTO"},"content":{"rendered":"<p>Kanguro love, love, love&#8230;<\/p>\n<p>Grazie per la foto a Niky, che nel bel mezzo di una vacanza a Canberra ha incontrato col suo compagno un simpatico amichetto molto affettuoso.<\/p>\n<p>Il Kanguro \u00e8 il simbolo dell&#8217;Australia e ed \u00e8 uno degli animali pi\u00f9 sensibili al mondo&#8230;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p><img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2016\/07\/FB_IMG_1468871812073.jpg\" alt=\"\" title=\"FB_IMG_1468871812073\" width=\"826\" height=\"960\" class=\"aligncenter size-full wp-image-91504\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2016\/07\/FB_IMG_1468871812073.jpg 826w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2016\/07\/FB_IMG_1468871812073-258x300.jpg 258w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2016\/07\/FB_IMG_1468871812073-768x893.jpg 768w\" sizes=\"(max-width: 826px) 100vw, 826px\" \/><\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2016\/07\/20\/grazie-per-la-foto-219\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2016\/07\/20\/grazie-per-la-foto-219\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>Kanguro love, love, love&#8230; Grazie per la foto a Niky, che nel bel mezzo di una vacanza a Canberra ha incontrato col suo compagno un simpatico amichetto molto affettuoso. Il Kanguro \u00e8 il simbolo dell&#8217;Australia e ed \u00e8 uno degli animali pi\u00f9 sensibili al mondo&#8230; &nbsp; &nbsp; &nbsp;<\/p>\n","protected":false},"author":4,"featured_media":91504,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[1,78],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/91503"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=91503"}],"version-history":[{"count":2,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/91503\/revisions"}],"predecessor-version":[{"id":91508,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/91503\/revisions\/91508"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/91504"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=91503"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=91503"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=91503"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}