{"id":91560,"date":"2016-07-19T14:49:54","date_gmt":"2016-07-19T12:49:54","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=91560"},"modified":"2016-07-19T18:13:56","modified_gmt":"2016-07-19T16:13:56","slug":"l-aggiornamento-della-protezione-civile-a-lecce","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2016\/07\/19\/l-aggiornamento-della-protezione-civile-a-lecce\/","title":{"rendered":"L&#8217; AGGIORNAMENTO DELLA PROTEZIONE CIVILE A LECCE"},"content":{"rendered":"<p><img decoding=\"async\" loading=\"lazy\" width=\"1024\" height=\"576\" title=\"maxresdefault\" class=\"alignleft size-large wp-image-91561\" alt=\"\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2016\/07\/maxresdefault2-1024x576.jpg\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2016\/07\/maxresdefault2-1024x576.jpg 1024w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2016\/07\/maxresdefault2-300x169.jpg 300w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2016\/07\/maxresdefault2-768x432.jpg 768w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2016\/07\/maxresdefault2.jpg 1280w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>Riceviamo e volentieri pubblichiamo. Cristian Carpentieri, dell&#8217; assessorato all&#8217; ambiente del Comune di Lecce, ci manda il seguente comunicato______<\/p>\n<p>Aggiornato ieri sera, con una Deliberazione di Consiglio Comunale, il Piano Comunale di Protezione Civile.<\/p>\n<p>Il vecchio Piano, risalente al 2008, \u00e8 stato rivisitato e adeguato a quelli che sono i nuovi assetti normativi e le nuove peculiarit\u00e0 del territorio e della sua popolazione, non solo quella residente.<\/p>\n<p>Negli ultimi anni il Servizio di Protezione Civile, che ha il compito di tutelare persone, beni, insediamenti ed ambiente dai danni, o dal pericolo di danni, causati da calamit\u00e0 naturali, catastrofi o altri eventi calamitosi, ha via via adottato un nuovo e pi\u00f9 moderno concetto di intervento, basato non pi\u00f9 solo sul soccorso alla popolazione in caso di eventi infausti, ma sulla combinazione di diverse attivit\u00e0 quali la previsione, la prevenzione e il soccorso, unitamente a tutte le altre finalizzate a ristabilire le condizioni di vita preesistenti gli stessi eventi catastrofici.<\/p>\n<p>\u201cIl Piano Comunale di Protezione Civile &#8211; fa sapere l\u2019Assessore al Ramo, Andrea Guido &#8211; \u00e8 l\u2019insieme coordinato delle misure da adottarsi in caso di eventi naturali ed umani che comportino rischi per la pubblica incolumit\u00e0 ed ha in se lo scopo di prevenire e contrastare gli eventi calamitosi e tutelare la vita dei cittadini, l\u2019ambiente e i beni pubblici e privati. Rappresenta uno strumento dinamico che deve essere periodicamente revisionato al fine di operare, in caso di emergenza, con cognizione di causa.<\/p>\n<p>Alla luce di una nuova normativa nazionale pi\u00f9 attenta alle criticit\u00e0 ma, soprattutto, pi\u00f9 attenta alla prevenzione &#8211; continua il membro della Giunta &#8211; abbiamo proceduto all\u2019aggiornamento del nostro piano comunale. Assetti urbanistici e idrogeologici, associazioni e volontari operativi di Protezione Civile, dopo 8 anni risultano diversi.<\/p>\n<p>Occorreva quindi rivedere un po\u2019 il tutto e adeguare le strategie di intervento ai nuovi assetti, soprattutto in riferimento a quei periodi dell\u2019anno in cui la presenza umana sul territorio cresce vertiginosamente per via del grande afflusso turistico. \u00c8 di estrema importanza per la tutela e la crescita della citt\u00e0 intera e del suo hinterland avere le idee chiare sulle procedure operative di intervento per fronteggiare qualsiasi calamit\u00e0. Il piano d\u2019emergenza \u00e8 lo strumento che consente alle autorit\u00e0 di predisporre e coordinare gli interventi di soccorso a tutela della popolazione e dei beni. Ma esso \u00e8 importante anche perch\u00e9 ha l\u2019obiettivo di garantire con ogni mezzo il mantenimento del livello di vita civile messo in crisi da una situazione che comporta gravi disagi fisici e psicologici. Era tra gli obbiettivi del mio mandato e per questo oggi non posso che esprimere grande soddisfazione.<\/p>\n<p>Ritengo &#8211; conclude Guido &#8211; che il nostro ora sia davvero un buon piano, sufficientemente flessibile per essere utilizzato in tutte le emergenze, incluse quelle impreviste, e semplice in modo da divenire rapidamente operativo\u201d.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2016\/07\/19\/l-aggiornamento-della-protezione-civile-a-lecce\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2016\/07\/19\/l-aggiornamento-della-protezione-civile-a-lecce\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>Riceviamo e volentieri pubblichiamo. Cristian Carpentieri, dell&#8217; assessorato all&#8217; ambiente del Comune di Lecce, ci manda il seguente comunicato______ Aggiornato ieri sera, con una Deliberazione di Consiglio Comunale, il Piano Comunale di Protezione Civile. Il vecchio Piano, risalente al 2008, \u00e8 stato rivisitato e adeguato a quelli che sono i nuovi assetti normativi e le [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":91561,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[36],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/91560"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=91560"}],"version-history":[{"count":2,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/91560\/revisions"}],"predecessor-version":[{"id":91563,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/91560\/revisions\/91563"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/91561"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=91560"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=91560"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=91560"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}