{"id":91887,"date":"2016-07-23T00:10:53","date_gmt":"2016-07-22T22:10:53","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=91887"},"modified":"2016-07-23T10:34:03","modified_gmt":"2016-07-23T08:34:03","slug":"diario-di-cotronei-arrigoni-mancosu-e-lepore-che-giocatori-lunedi-la-presentazione-della-campagna-abbonamenti","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2016\/07\/23\/diario-di-cotronei-arrigoni-mancosu-e-lepore-che-giocatori-lunedi-la-presentazione-della-campagna-abbonamenti\/","title":{"rendered":"DIARIO DI COTRONEI \/ IL NUOVO &#8216;REGISTA&#8217; ANDREA ARRIGONI: &#8220;Mancosu e Lepore, che gran bei giocatori!&#8221;"},"content":{"rendered":"<p>di <strong>Francesco Giannetta<\/strong> ______<\/p>\n<p>Pomeriggio di riposo per i ragazzi agli ordini di mister <strong>Padalino<\/strong> in vista dell&#8217;amichevole che domani li vedr\u00e0 impegnati alle ore 17.00 contro la <strong>Rappresentativa Camigliatello Silano<\/strong>, squadra formata da giocatori che militano in Eccellenza e Promozione con alcuni innesti di serie D. In mattinata il lavoro in palestra ha anticipato alcune esercitazioni tecnico-tattiche. Domani, e ancora di pi\u00f9, domenica 31 contro l&#8217;<strong>Altovicentino<\/strong> nel primo turno di <strong>Tim Cup<\/strong>, sar\u00e0 necessario mettere in pratica quanto appreso in questi giorni di ritiro calabro.<\/p>\n<p><img decoding=\"async\" loading=\"lazy\" width=\"980\" height=\"735\" title=\"lecce-ritiro-allenamento-2\" class=\"aligncenter size-full wp-image-91888\" alt=\"\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2016\/07\/lecce-ritiro-allenamento-2.jpg\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2016\/07\/lecce-ritiro-allenamento-2.jpg 980w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2016\/07\/lecce-ritiro-allenamento-2-300x225.jpg 300w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2016\/07\/lecce-ritiro-allenamento-2-768x576.jpg 768w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2016\/07\/lecce-ritiro-allenamento-2-400x300.jpg 400w\" sizes=\"(max-width: 980px) 100vw, 980px\" \/><\/p>\n<p>Anche <strong>Andrea Arrigoni<\/strong>, nuovo regista giallorosso, la pensa in questo modo: <em>\u201cIn questa fase stiamo lavorando tanto com\u2019\u00e8 giusto che sia. Questo periodo ci permette di approfondire\u00a0la conoscenza tra di noi, vivendo tutto il giorno insieme, e il gruppo si sta formando. Come avevo avuto\u00a0modo di dire in precedenza, non conoscevo personalmente i miei nuovi compagni, ma dopo questi primi\u00a0giorni di ritiro posso dire che sono tutti dei bravi ragazzi. Ad ora abbiamo disputato solo un test\u00a0amichevole. Nella prima uscita abbiamo cercato di mettere in pratica quei concetti che abbiamo\u00a0sviluppato con mister Padalino in questi allenamenti. Sicuramente sono dei test che diciamo cos\u00ec\u00a0lasciano il tempo che trovano, ma sono utili per mettere in pratica quello che proviamo e, comunque, in campo si \u00e8 vista qualche buona giocata. Le parole d\u2019apprezzamento di mister Roselli su di me? Con lui ho vissuto un bel periodo a Cosenza, ci lega un rapporto di grande stima reciproca. Nell\u2019ultima annata non ho saltato neanche un minuto nelle gare di campionato, spero di avere questa costanza anche in maglia giallorossa. Chi mi ha impressionato dei nuovi compagni? Premesso che siamo un ottimo gruppo, dico che Mancosu e Lepore sono due giocatori con dei numeri importanti, hanno qualit\u00e0 e gamba per fare\u00a0molto bene.\u201d<\/em><\/p>\n<p><img decoding=\"async\" loading=\"lazy\" width=\"300\" height=\"199\" title=\"arrigoni-2\" class=\"alignleft size-medium wp-image-91889\" alt=\"\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2016\/07\/arrigoni-2-300x199.jpg\" \/><\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2016\/07\/23\/diario-di-cotronei-arrigoni-mancosu-e-lepore-che-giocatori-lunedi-la-presentazione-della-campagna-abbonamenti\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2016\/07\/23\/diario-di-cotronei-arrigoni-mancosu-e-lepore-che-giocatori-lunedi-la-presentazione-della-campagna-abbonamenti\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>di Francesco Giannetta ______ Pomeriggio di riposo per i ragazzi agli ordini di mister Padalino in vista dell&#8217;amichevole che domani li vedr\u00e0 impegnati alle ore 17.00 contro la Rappresentativa Camigliatello Silano, squadra formata da giocatori che militano in Eccellenza e Promozione con alcuni innesti di serie D. In mattinata il lavoro in palestra ha anticipato [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":91888,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[28],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/91887"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=91887"}],"version-history":[{"count":5,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/91887\/revisions"}],"predecessor-version":[{"id":91893,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/91887\/revisions\/91893"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/91888"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=91887"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=91887"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=91887"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}