{"id":91972,"date":"2016-07-24T00:07:30","date_gmt":"2016-07-23T22:07:30","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=91972"},"modified":"2016-07-23T20:14:35","modified_gmt":"2016-07-23T18:14:35","slug":"diario-del-giorno-prima-il-tam-tam-di-annibale-138","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2016\/07\/24\/diario-del-giorno-prima-il-tam-tam-di-annibale-138\/","title":{"rendered":"DIARIO DEL GIORNO PRIMA \/ IL TAM TAM DI ANNIBALE"},"content":{"rendered":"<p>ITALIA______<\/p>\n<div><strong>NOVARA &#8211; <\/strong>Litiga con la compagna e la uccide a coltellate. \u00c8 accaduto oggi pomeriggio nel centro di Novara. La coppia, lei italiana lui marocchino, hanno discusso nella loro abitazione, in corso Cavour. Dalle parole, l&#8217;uomo \u00e8 passato ai fatti: ha afferrato un coltello e l&#8217;ha colpita pi\u00f9 volte. La donna ha avuto la forza di scendere in strada, nell&#8217;affollato corso pedonale, per chiedere aiuto. Le ferite, per\u00f2, erano troppo gravi: la donna \u00e8 morta all&#8217;arrivo dei soccorsi. Sul posto anche la polizia, che ha arrestato il marocchino.<\/div>\n<p>ITALIA______<\/p>\n<div><strong>MONZA \/ BRIANZA &#8211; <\/strong>Una banda dedita alle truffe online di case-vacanza \u00e8 stata sgominata dalla Polizia di Stato, che ha denunciato ventidue persone. Gli indagati avevano messo in piedi un articolato sistema di raggiri per affittare appartamenti inesistenti, o di cui non avevano la disponibilit\u00e0, locandoli persino a pi\u00f9 famiglie contemporaneamente. Le indagini, condotte dal Compartimento della Polizia postale e delle comunicazioni di Milano, a seguito di alcune denunce, sono riuscite a risalire dal web ai responsabili reali, a cui sono contestati almeno seicento casi di raggiro, duecentocinquanta dei quali a Milano. Il gruppo criminale &#8216;affittava&#8217; appartamenti nelle pi\u00f9 rinomate localit\u00e0 di villeggiatura, sulle Riviere o in prestigiose localit\u00e0 montane.<\/div>\n<p><img decoding=\"async\" loading=\"lazy\" kasperskylab_antibanner=\"on\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2016\/07\/475x255_1469277648146.GettyImages_579205484-300x161.jpg\" alt=\"\" title=\"475x255_1469277648146.GettyImages_579205484\" class=\"alignleft size-medium wp-image-91974\" height=\"161\" width=\"300\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2016\/07\/475x255_1469277648146.GettyImages_579205484-300x161.jpg 300w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2016\/07\/475x255_1469277648146.GettyImages_579205484.jpg 475w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>MONDO______<\/p>\n<p><strong>KABUL &#8211;<\/strong> Almeno ottanta morti e duecentotrenta feriti. E&#8217; gravissimo il bilancio di un attentato suicida sferrato a Kabul, in Afghanistan. Un kamikaze si \u00e8 fatto esplodere durante una manifestazione di Hazara sciiti, provocando la strage. L&#8217;isis ha rivendicato la responsabilit\u00e0 dell&#8217;attentato attraverso la sua agenzia Aamaq. I talebani afghani avevano negato di essere responsabili e il portavoce degli insorti, Zabihullah Mujahid, ha sottolineato in un comunicato che l&#8217;attentato &#8220;\u00e8 una cospirazione di chi vuole la divisione del popolo afghano&#8221;. Secondo un testimone oculare che ha rilasciato la dichiarazione a Tolo Tv, il kamikaze indossava un burqa. I numerosi container dislocati dalle forze di sicurezza per sbarrare l&#8217;accesso al centro della citt\u00e0 hanno reso difficilissimo il lavoro dei soccorritori, al punto che numerosi cadaveri giacevano sull&#8217;asfalto ancora ore dopo l&#8217;esplosione.<\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2016\/07\/24\/diario-del-giorno-prima-il-tam-tam-di-annibale-138\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2016\/07\/24\/diario-del-giorno-prima-il-tam-tam-di-annibale-138\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>ITALIA______ NOVARA &#8211; Litiga con la compagna e la uccide a coltellate. \u00c8 accaduto oggi pomeriggio nel centro di Novara. La coppia, lei italiana lui marocchino, hanno discusso nella loro abitazione, in corso Cavour. Dalle parole, l&#8217;uomo \u00e8 passato ai fatti: ha afferrato un coltello e l&#8217;ha colpita pi\u00f9 volte. La donna ha avuto la [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":91974,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[1,69,76],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/91972"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=91972"}],"version-history":[{"count":5,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/91972\/revisions"}],"predecessor-version":[{"id":91976,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/91972\/revisions\/91976"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/91974"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=91972"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=91972"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=91972"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}