{"id":92009,"date":"2025-07-25T00:01:00","date_gmt":"2025-07-24T22:01:00","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=92009"},"modified":"2025-07-24T11:21:25","modified_gmt":"2025-07-24T09:21:25","slug":"buongiorno-per-tutto-il-giorno-243","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2025\/07\/25\/buongiorno-per-tutto-il-giorno-243\/","title":{"rendered":"DIARIO DEL GIORNO \/ VENERDI&#8217; 25 LUGLIO 2025"},"content":{"rendered":"<p>Buongiorno!<\/p>\n<p>Oggi \u00e8 venerd\u00ec 25 luglio 2025.<\/p>\n<p>San Giacomo.<\/p>\n<p>Auguri di buon onomastico a chi porta questo nome!<\/p>\n<p>A Lecce, la nostra amica Marika Serra compie 25 anni: buon compleanno!<\/p>\n<p><img decoding=\"async\" loading=\"lazy\" class=\"alignleft size-medium wp-image-92010\" title=\"fascismo-riassunto\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2016\/07\/fascismo-riassunto-300x200.jpg\" alt=\"\" width=\"300\" height=\"200\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2016\/07\/fascismo-riassunto-300x200.jpg 300w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2016\/07\/fascismo-riassunto.jpg 600w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>Come oggi, nel 1943, dopo una riunione della durata di\u00a0dieci ore, tenuta nella sede del Gran Consiglio del Fascismo a Palazzo Venezia, viene approvato l&#8217;ordine del giorno presentato da Dino Grandi e vengono cos\u00ec restituiti tutti i poteri politici e militari nelle mani di Vittorio Emanuele III e degli organi costituzionali.<\/p>\n<p>I fautori di questa manovra voluta per ridimensionare il potere di Benito Mussolini, a causa anche delle poche fortune che l&#8217;Italia aveva avuto in guerra, furono il i Gerarchi fascisti come Grandi, Ciano e Bottai.<\/p>\n<p>Alle ore 17 del 25 luglio, dopo aver incontrato il Re a villa Savoia, Mussolini viene arrestato da due Carabinieri:\u00a0Paolo Vigneri e Raffaele Aversa.<\/p>\n<p>Il Re incarica Badoglio di formare un nuovo governo.<\/p>\n<p>Proverbio salentino: <strong>CI CHIANTA UNGULI MANGIA FAE<\/strong><br \/>\nChi mette a dimora la piantina della fava ne manger\u00e0 il frutto.<br \/>\nIn altre parole ognuno raccoglie ci\u00f2 che semina.<\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2025\/07\/25\/buongiorno-per-tutto-il-giorno-243\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2025\/07\/25\/buongiorno-per-tutto-il-giorno-243\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>Buongiorno! Oggi \u00e8 venerd\u00ec 25 luglio 2025. San Giacomo. Auguri di buon onomastico a chi porta questo nome! A Lecce, la nostra amica Marika Serra compie 25 anni: buon compleanno! Come oggi, nel 1943, dopo una riunione della durata di\u00a0dieci ore, tenuta nella sede del Gran Consiglio del Fascismo a Palazzo Venezia, viene approvato l&#8217;ordine [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":92010,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[1],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/92009"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=92009"}],"version-history":[{"count":14,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/92009\/revisions"}],"predecessor-version":[{"id":246382,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/92009\/revisions\/246382"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/92010"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=92009"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=92009"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=92009"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}