{"id":92130,"date":"2016-07-26T10:08:59","date_gmt":"2016-07-26T08:08:59","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=92130"},"modified":"2016-07-26T14:13:24","modified_gmt":"2016-07-26T12:13:24","slug":"i-bus-ridotti-ad-agosto-a-lecce-citta","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2016\/07\/26\/i-bus-ridotti-ad-agosto-a-lecce-citta\/","title":{"rendered":"I BUS RIDOTTI AD AGOSTO A LECCE CITTA&#8217;"},"content":{"rendered":"<p><img decoding=\"async\" loading=\"lazy\" width=\"300\" height=\"250\" title=\"sgm\" class=\"aligncenter size-medium wp-image-92131\" alt=\"\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2016\/07\/sgm-300x250.jpg\" \/>Riceviamo e volentieri pubblichiamo. L&#8217; ufficio &#8211; stampa dell&#8217; associazione Laica ci manda il seguente comunicato______<\/p>\n<p>\u201cBus SGM: ad agosto le corse ridotte del 50% e attese infinite per i leccesi che devono raggiungere il centro\u201d \u2013 \u00e8 la denuncia della dott.ssa Silvia Pispico, vicepresidente dell\u2019Associazione Laica che evidenzia i disservizi generati dalla riduzione della linea urbana 27 che, per intenderci, prevede il seguente percorso: Citt\u00e0 di Lecce (Capolinea), V. Monteroni, Ecotekne, V. Monteroni, V. Massaglia, P.le Rudiae, V. Diaz, V.le Gallipoli, Stazione F.F.S.S., V.le Otranto, V. Cavallotti, V.le De Pietro, V.le Calasso (Porta Napoli), V.le dell&#8217;Universit\u00e0, Via De Jacobis, Via Massaglia, V. Monteroni, Citt\u00e0 di Lecce.<\/p>\n<p>\u201cLa riduzione della frequenza della linea 27 \u2013 afferma Silvia Pispico \u2013 \u00e8 senz\u2019altro dovuta ad una minore affluenza di studenti che devono raggiungere l\u2019Ecotekne. Ci\u00f2 per\u00f2 non \u00e8 giustificabile perch\u00e9 crea un grave disservizio in quanto quella linea non \u00e8 utilizzata solo dagli studenti ma da tanti cittadini che ogni giorno devono raggiungere il centro cittadino. Ci sono commesse, impiegati e leccesi che per svariati motivi non possono prendere il bus se non dopo aver atteso tanto tempo sotto la fermata.<\/p>\n<p>La libert\u00e0 \u2013 continua Silvia Pispico &#8211; non \u00e8 un concetto astratto, ma si esplica anche nella vita di tutti i giorni dando la possibilit\u00e0 ad un cittadino di spostarsi nel pi\u00f9 breve tempo possibile, nella propria citt\u00e0 di cui oltre a pagare il biglietto \u00e8 contribuente. Ci\u00f2 che accadr\u00e0 a Lecce nel mese di Agosto per quanto riguarda i trasporti \u00e8 alquanto grave. Ridurre il numero delle corse urbane in una citt\u00e0 produttiva come Lecce, per il semplice fatto che l\u2019universit\u00e0 sospender\u00e0 per il periodo estivo le lezioni, \u00e8 contraria ad ogni logica di buon senso. Creare un disservizio ai cittadini pendolari, alle attivit\u00e0 commerciali, alle associazioni, alle caserme, alle cliniche private e ai turisti che decidono di soggiornare nella periferia della nostra citt\u00e0 risulta un modo primitivo di gestire un servizio di prima necessit\u00e0. In qualit\u00e0 di vice presidente dell\u2019associazione Laica chiedo quantomeno che i tempi di attesa si riducano al massimo ai 30 minuti.\u201d<\/p>\n<p>&nbsp;<\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2016\/07\/26\/i-bus-ridotti-ad-agosto-a-lecce-citta\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2016\/07\/26\/i-bus-ridotti-ad-agosto-a-lecce-citta\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>Riceviamo e volentieri pubblichiamo. L&#8217; ufficio &#8211; stampa dell&#8217; associazione Laica ci manda il seguente comunicato______ \u201cBus SGM: ad agosto le corse ridotte del 50% e attese infinite per i leccesi che devono raggiungere il centro\u201d \u2013 \u00e8 la denuncia della dott.ssa Silvia Pispico, vicepresidente dell\u2019Associazione Laica che evidenzia i disservizi generati dalla riduzione della [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":92131,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[36],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/92130"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=92130"}],"version-history":[{"count":2,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/92130\/revisions"}],"predecessor-version":[{"id":92133,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/92130\/revisions\/92133"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/92131"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=92130"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=92130"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=92130"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}