{"id":92139,"date":"2016-07-26T10:29:09","date_gmt":"2016-07-26T08:29:09","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=92139"},"modified":"2016-07-26T14:27:08","modified_gmt":"2016-07-26T12:27:08","slug":"il-degrado-del-parco-osanna-ad-arnesano","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2016\/07\/26\/il-degrado-del-parco-osanna-ad-arnesano\/","title":{"rendered":"IL DEGRADO DEL PARCO OSANNA AD ARNESANO"},"content":{"rendered":"<p><img decoding=\"async\" loading=\"lazy\" width=\"1024\" height=\"768\" title=\"a\" class=\"aligncenter size-large wp-image-92140\" alt=\"\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2016\/07\/a1-1024x768.jpg\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2016\/07\/a1-1024x768.jpg 1024w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2016\/07\/a1-300x225.jpg 300w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2016\/07\/a1-768x576.jpg 768w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2016\/07\/a1-400x300.jpg 400w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2016\/07\/a1.jpg 1280w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>Riceviamo e volentieri pubblichiamo. Da Arnesano Jacopo Caroppo del M5S ci scrive______<\/p>\n<p>Segnalazioni arrivano dai cittadini di Arnesano sullo stato del Parco Osanna per le condizioni di abbandono e incuria di un\u2019area frequentata, soprattutto, da ragazzi e bambini di diverse et\u00e0. Strutture adibite per far giocare i bambini rotte, un\u2019altalena manca proprio, pavimentazione dissestata, l\u2019erba incolta e rinsecchita dal sole, vialetti pericolosi e sporcizia ovunque.<\/p>\n<p>\u201cRicordiamo \u2013 dichiarano i componenti del meetup Arnesano 5 Stelle &#8211; che il programma dell\u2019attuale amministrazione prevede la salvaguardia l\u2019ambiente e, di raccordo con la scuola e con le altre associazioni presenti sul territorio, l\u2019incentivazione all\u2019educazione dei ragazzi ad amare il nostro ambiente. Ma come si pu\u00f2 pensare di fare questo se gli spazi verdi presenti, nel nostro comune, si trovano in queste condizioni precarie. Il parco Osanna che dovrebbe essere un polmone verde per il paese, negli anni \u00e8 diventato solo oggetto di atti vandalici. A questo punto ci si chiede in quale luogo sicuro sia possibile portare i bambini a giocare; dovrebbe essere di assoluta priorit\u00e0 la messa in sicurezza in tempi brevi dell\u2019area.\u201d<\/p>\n<p>&nbsp;<\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2016\/07\/26\/il-degrado-del-parco-osanna-ad-arnesano\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2016\/07\/26\/il-degrado-del-parco-osanna-ad-arnesano\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>Riceviamo e volentieri pubblichiamo. Da Arnesano Jacopo Caroppo del M5S ci scrive______ Segnalazioni arrivano dai cittadini di Arnesano sullo stato del Parco Osanna per le condizioni di abbandono e incuria di un\u2019area frequentata, soprattutto, da ragazzi e bambini di diverse et\u00e0. Strutture adibite per far giocare i bambini rotte, un\u2019altalena manca proprio, pavimentazione dissestata, l\u2019erba [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":92140,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[36],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/92139"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=92139"}],"version-history":[{"count":3,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/92139\/revisions"}],"predecessor-version":[{"id":92143,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/92139\/revisions\/92143"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/92140"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=92139"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=92139"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=92139"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}