{"id":93113,"date":"2016-08-03T21:01:53","date_gmt":"2016-08-03T19:01:53","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=93113"},"modified":"2016-08-03T21:01:53","modified_gmt":"2016-08-03T19:01:53","slug":"arrestato-e-portato-in-carcere-uomo-che-picchia-la-compagna-a-gallipoli-dove-la-coppia-era-in-ferie","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2016\/08\/03\/arrestato-e-portato-in-carcere-uomo-che-picchia-la-compagna-a-gallipoli-dove-la-coppia-era-in-ferie\/","title":{"rendered":"ARRESTATO E PORTATO IN CARCERE UOMO CHE PICCHIA LA COMPAGNA A GALLIPOLI, DOVE LA COPPIA ERA IN FERIE"},"content":{"rendered":"<p><img decoding=\"async\" loading=\"lazy\" width=\"300\" height=\"225\" title=\"polizia-stradale-notte\" class=\"alignleft size-medium wp-image-93114\" alt=\"\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2016\/08\/polizia-stradale-notte-300x225.jpg\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2016\/08\/polizia-stradale-notte-300x225.jpg 300w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2016\/08\/polizia-stradale-notte-1024x768.jpg 1024w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2016\/08\/polizia-stradale-notte-768x576.jpg 768w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2016\/08\/polizia-stradale-notte-1536x1152.jpg 1536w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2016\/08\/polizia-stradale-notte-400x300.jpg 400w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2016\/08\/polizia-stradale-notte.jpg 1600w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>(g.m.)______Erano in ferie a Gallipoli, ma qualcosa non \u00e8 andato bene fra di loro. Questo \u00e8 bastato all&#8217; uomo che\u00a0ha cominciato a picchiare per strada la sua compagna convivente, di 42 anni. L&#8217; ha presa a calci, a pugni, l&#8217; ha scaraventata per terra, le ha sottratto il bancomat, l&#8217; ha colpita nuovamente al capo, sotto gli occhi terrorizzati del figlio minorenne, e dei numerosi passanti, che hanno chiamato il 113.<\/p>\n<p>Gli agenti di una volante sono arrivati in tempo utile per evitare il peggio.<\/p>\n<p>La donna \u00e8 stata portata in ospedale, dove le sono state prestate le prime cure: ha avuto una prognosi di cinque giorni.<\/p>\n<p>L&#8217;uomo, \u00e8 stato arrestato e portato in carcere a borgo San Nicola.<\/p>\n<p>In ossequio alle disposizioni di legge vigenti in materia, a tutela della vittima e del minore, sono state omessi tutti i riferimenti di identit\u00e0 specifici.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2016\/08\/03\/arrestato-e-portato-in-carcere-uomo-che-picchia-la-compagna-a-gallipoli-dove-la-coppia-era-in-ferie\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2016\/08\/03\/arrestato-e-portato-in-carcere-uomo-che-picchia-la-compagna-a-gallipoli-dove-la-coppia-era-in-ferie\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>(g.m.)______Erano in ferie a Gallipoli, ma qualcosa non \u00e8 andato bene fra di loro. Questo \u00e8 bastato all&#8217; uomo che\u00a0ha cominciato a picchiare per strada la sua compagna convivente, di 42 anni. L&#8217; ha presa a calci, a pugni, l&#8217; ha scaraventata per terra, le ha sottratto il bancomat, l&#8217; ha colpita nuovamente al capo, [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":93114,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[69],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/93113"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=93113"}],"version-history":[{"count":2,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/93113\/revisions"}],"predecessor-version":[{"id":93116,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/93113\/revisions\/93116"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/93114"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=93113"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=93113"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=93113"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}