{"id":93643,"date":"2016-08-10T00:07:16","date_gmt":"2016-08-09T22:07:16","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=93643"},"modified":"2016-08-09T11:40:11","modified_gmt":"2016-08-09T09:40:11","slug":"diario-del-giorno-prima-il-tam-tam-di-annibale-152","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2016\/08\/10\/diario-del-giorno-prima-il-tam-tam-di-annibale-152\/","title":{"rendered":"DIARIO DEL GIORNO PRIMA \/ IL TAM TAM DI ANNIBALE"},"content":{"rendered":"<p>ITALIA______<br \/>\nVENTIMIGLIA &#8211; La situazione si fa sempre pi\u00f9 esplosiva, mancando come lamentano in molti, un piano nazionale di accoglienza. Da settimane molti sindaci segnalano a Roma che non hanno a disposizione strutture adeguate e sufficienti per accogliere tutti coloro che arrivano in Italia. Per non parlare dei minori non accompagnati che debbono essere assistiti da personale qualificato. E non sempre questo servizio pu\u00f2 essere assicurato. Particolarmente difficile la situazione in questi giorni a Ventimiglia, in Liguria dove centinaia di migranti stanno cercando di entrare in Francia. &#8220;Intensificheremo le operazioni di decompressione per alleggerire la pressione, prendendo le persone e portandole da un\u2019altra parte&#8221;: \u00e8 quanto ha affermato il capo della polizia, il prefetto Franco Gabrielli, oggi in visita in Liguria per discutere dei colleghi della situazione.<\/p>\n<p>ITALIA______<br \/>\nSUDAN ITALIA &#8211; Professori nuovamente in piazza oggi in alcune citt\u00e0 del sud, come Bari, Potenza, Catania, come nei giorni scorsi. La protesta nasce dai meccanismi di assegnazione che costringono molti di loro a cambiare sede spostandosi anche di centinaia di chilometri. Intanto, il Ministro dell&#8217;Istruzione Stefania Giannini annuncia che un totale di Trentaduemila insegnanti entreranno in ruolo da settembre e saranno sbloccate diecimila assunzioni per il personale Ata.<\/p>\n<p><img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2016\/08\/310x0_1469885225497.rainews_20160730152534941-300x200.jpg\" alt=\"\" title=\"310x0_1469885225497.rainews_20160730152534941\" width=\"300\" height=\"200\" class=\"alignleft size-medium wp-image-93644\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2016\/08\/310x0_1469885225497.rainews_20160730152534941-300x200.jpg 300w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2016\/08\/310x0_1469885225497.rainews_20160730152534941.jpg 310w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>MONDO______<br \/>\nALEPPO (SIRIA) &#8211; Pi\u00f9 di due milioni di persone in Aleppo nel Nord della Siria rischiano di finire sotto un assedio totale. E&#8217; quanto avvertono le Nazioni Unite che chiedono l&#8217;accesso immediato alla seconda citt\u00e0 del Paese pesantemente bombardata. In due settimane di violenti combattimenti il capoluogo \u00e8 diviso in due parti con i ribelli dell&#8217;opposizione da una parte e le forze del regime dall&#8217;altra che controllano le vie di accesso del nemico ponendo di conseguenza i residenti civili sotto assedio. In una dichiarazione diffusa oggi, un ufficiale delle Nazioni Unite per gli aiuti umanitari in Siria, Yacoub El Hillo, e il coordinatore regionale Kevin Kennedy hanno fatto un appello per una &#8220;pausa umanitaria&#8221; nelle ostilit\u00e0.<\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2016\/08\/10\/diario-del-giorno-prima-il-tam-tam-di-annibale-152\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2016\/08\/10\/diario-del-giorno-prima-il-tam-tam-di-annibale-152\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>ITALIA______ VENTIMIGLIA &#8211; La situazione si fa sempre pi\u00f9 esplosiva, mancando come lamentano in molti, un piano nazionale di accoglienza. Da settimane molti sindaci segnalano a Roma che non hanno a disposizione strutture adeguate e sufficienti per accogliere tutti coloro che arrivano in Italia. Per non parlare dei minori non accompagnati che debbono essere assistiti [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":93644,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[1,69,76],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/93643"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=93643"}],"version-history":[{"count":1,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/93643\/revisions"}],"predecessor-version":[{"id":93645,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/93643\/revisions\/93645"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/93644"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=93643"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=93643"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=93643"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}