{"id":94343,"date":"2016-08-15T11:26:09","date_gmt":"2016-08-15T09:26:09","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=94343"},"modified":"2016-08-15T11:31:27","modified_gmt":"2016-08-15T09:31:27","slug":"muore-dopo-un-giro-sulle-giostre-ad-alezio-ferragosto-maledetto-per-un-ragazzo-quindicenne","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2016\/08\/15\/muore-dopo-un-giro-sulle-giostre-ad-alezio-ferragosto-maledetto-per-un-ragazzo-quindicenne\/","title":{"rendered":"MUORE DOPO UN GIRO SULLE GIOSTRE AD ALEZIO, FERRAGOSTO MALEDETTO PER UN RAGAZZO QUINDICENNE"},"content":{"rendered":"<p><img decoding=\"async\" loading=\"lazy\" width=\"720\" height=\"540\" title=\"SAM_0890\" class=\"alignleft size-full wp-image-94345\" alt=\"\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2016\/08\/SAM_08901.jpg\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2016\/08\/SAM_08901.jpg 720w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2016\/08\/SAM_08901-300x225.jpg 300w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2016\/08\/SAM_08901-400x300.jpg 400w\" sizes=\"(max-width: 720px) 100vw, 720px\" \/>(e.l.)______Era andato alle giostre, ad Alezio, il suo paese, alla festa della Madonna della Lizza, ieri sera.<\/p>\n<p>Verso le 23, era salito sul cos\u00ec detto tagad\u00e0 (nella foto d\u2019 archivio, un\u2019 immagine di repertorio), una specie di\u00a0cerchio concentrico, che gira su s\u00e9 stesso e con vari movimenti in verticale e in orizzontale,\u00a0con i divanetti fissati dentro, ai bordi,\u00a0ad accogliere i partecipanti, che spesso si alzano e sfidano l\u2019 equilibrio, per qualche minuto di divertenti vertigini, di brividi da adrenalina.<\/p>\n<p>Ma qualcosa non \u00e8 andata bene. Lo devono accertare le indagini, gi\u00e0 avviate dai Carabinieri.<\/p>\n<p>Di sicuro, si \u00e8 sentito male, forse per\u00a0un colpo al torace\u00a0preso\u00a0sulla sbarra di ferro intorno alla giostra, che girava vorticosamente.<\/p>\n<p>E\u2019 stato soccorso, era qualcosa di grave, lo hanno capito subito tutti.<\/p>\n<p>Il ragazzo \u00e8 stato portato d\u2019 urgenza all\u2019 ospedale \u2018Vito Fazzi\u2019 di Lecce.<\/p>\n<p>Ma \u00e8 morto nel corso della notte.<\/p>\n<p>Samuele Piro aveva solo quindici anni.<\/p>\n<p>Il pubblico ministero di turno presso la procura della Repubblica di Lecce, Emilio Arnesano, ha disposto il sequestro dell\u2019 impianto, di propriet\u00e0 di un giostraio di Gallipoli.<\/p>\n<p>&nbsp;<\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2016\/08\/15\/muore-dopo-un-giro-sulle-giostre-ad-alezio-ferragosto-maledetto-per-un-ragazzo-quindicenne\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2016\/08\/15\/muore-dopo-un-giro-sulle-giostre-ad-alezio-ferragosto-maledetto-per-un-ragazzo-quindicenne\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>(e.l.)______Era andato alle giostre, ad Alezio, il suo paese, alla festa della Madonna della Lizza, ieri sera. Verso le 23, era salito sul cos\u00ec detto tagad\u00e0 (nella foto d\u2019 archivio, un\u2019 immagine di repertorio), una specie di\u00a0cerchio concentrico, che gira su s\u00e9 stesso e con vari movimenti in verticale e in orizzontale,\u00a0con i divanetti fissati [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":94345,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[69],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/94343"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=94343"}],"version-history":[{"count":5,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/94343\/revisions"}],"predecessor-version":[{"id":94347,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/94343\/revisions\/94347"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/94345"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=94343"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=94343"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=94343"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}