{"id":96814,"date":"2016-09-09T17:16:54","date_gmt":"2016-09-09T15:16:54","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=96814"},"modified":"2016-09-09T17:16:54","modified_gmt":"2016-09-09T15:16:54","slug":"lecce-alla-scoperta-di-giuseppe-torromino","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2016\/09\/09\/lecce-alla-scoperta-di-giuseppe-torromino\/","title":{"rendered":"LECCE \/ ALLA SCOPERTA DI&#8230; GIUSEPPE TORROMINO"},"content":{"rendered":"<p>di <strong>Francesco Giannetta<\/strong> ______<\/p>\n<p><img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2016\/09\/13925185_918511371610019_1962024272004316798_n.jpg\" alt=\"\" title=\"13925185_918511371610019_1962024272004316798_n\" width=\"640\" height=\"298\" class=\"aligncenter size-full wp-image-96846\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2016\/09\/13925185_918511371610019_1962024272004316798_n.jpg 640w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2016\/09\/13925185_918511371610019_1962024272004316798_n-300x140.jpg 300w\" sizes=\"(max-width: 640px) 100vw, 640px\" \/><\/p>\n<p>Un inizio di campionato da incorniciare per <strong>Giuseppe Torromino.<\/strong>\u00a0Con tre gol in due partite in Lega Pro e un gol nella presenza in Coppa Italia, il nuovo esterno d&#8217;attacco giallorosso si sta rivelando un giocatore chiave nello scacchiere di mister Padalino. Il suo gol in rovesciata dopo l&#8217;iniziale vantaggio dell&#8217;Akragas ha stregato tutti i 12.000 presenti al &#8220;Via del Mare&#8221;, un gesto tecnico e atletico di pregevole fattura per una rete che va di diritto sul podio delle pi\u00f9 belle realizzate in questo turno di <strong>Lega Pro<\/strong>.<\/p>\n<p>Torromino, nato a Crotone il 21 giugno del 1988, \u00e8 arrivato al <strong>Lecce<\/strong> il 4 agosto del 2016 proprio dal Crotone, club della sua citt\u00e0 natale. Soprannominato &#8220;Hulk&#8221; per via del suo fisico importante e per la grinta che mette ogni volta che scende in campo, in carriera ha vestito le maglie di Biellese, Torino, Carrarese, Treviso, Crotone, Virtus Entella e Grosseto prima di arrivare in salento. Ha vinto per due volte la Serie D, con la Biellese e con il Treviso, club con il quale ha vinto anche la Lega Pro Seconda Divisione, e una <strong>Lega Pro Prima Divisione<\/strong> con la Virtus Entella nella stagione 2013-2014.<\/p>\n<p>Quella contro l&#8217;Akragas non \u00e8 la sua prima doppietta in carriera. In altre due occasioni \u00e8 riuscito nel compito di realizzare due reti in un solo incontro, in Lega Pro con la maglia del Grosseto l&#8217;1 febbraio 2015 contro la Carrarese nell&#8217;incontro poi vinto per 2 a 1, e nel match dell&#8217;8 settembre 2013 pareggiato dal suo Crotone contro il Pescara per 2 a 2. Nella partita d&#8217;esordio in maglia giallorossa ha segnato anche su rigore, altra sua specialit\u00e0, in carriera infatti ha segnato un totale di 10 calci di rigore sbagliando in una sola occasione, contro il Bari, ma non condizionando negativamente il risultato di quella partita che il Crotone vinse con il punteggio di 2 a 1.<\/p>\n<p>&nbsp;<\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2016\/09\/09\/lecce-alla-scoperta-di-giuseppe-torromino\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2016\/09\/09\/lecce-alla-scoperta-di-giuseppe-torromino\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>di Francesco Giannetta ______ Un inizio di campionato da incorniciare per Giuseppe Torromino.\u00a0Con tre gol in due partite in Lega Pro e un gol nella presenza in Coppa Italia, il nuovo esterno d&#8217;attacco giallorosso si sta rivelando un giocatore chiave nello scacchiere di mister Padalino. Il suo gol in rovesciata dopo l&#8217;iniziale vantaggio dell&#8217;Akragas ha [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":96846,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[28],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/96814"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=96814"}],"version-history":[{"count":1,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/96814\/revisions"}],"predecessor-version":[{"id":96847,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/96814\/revisions\/96847"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/96846"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=96814"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=96814"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=96814"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}