{"id":9736,"date":"2013-01-07T09:28:15","date_gmt":"2013-01-07T09:28:15","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=9736"},"modified":"2013-01-07T09:28:15","modified_gmt":"2013-01-07T09:28:15","slug":"olio-nettare-degli-dei-arriva-nectarea","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2013\/01\/07\/olio-nettare-degli-dei-arriva-nectarea\/","title":{"rendered":"OLIO NETTARE DEGLI DEI\/ Arriva Nectarea"},"content":{"rendered":"<p><strong><a href=\"https:\/\/www.leccecronaca.it\/index.php\/2013\/01\/07\/olio-nettare-degli-dei-arriva-nectarea\/image001-5\/\" rel=\"attachment wp-att-9737\"><img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2013\/01\/image001-5-150x150.jpg\" alt=\"\" width=\"150\" height=\"150\" class=\"alignleft size-thumbnail wp-image-9737\" \/><\/a>Piccolo spazio pubblicit\u00e0 (gratuito)\u2026<\/strong><\/p>\n<p>E\u2019 risaputo che le propriet\u00e0 e le qualit\u00e0 dell\u2019olio extravergine d\u2019oliva vanno ben oltre il semplice condimento in cucina. Nasce adesso un prodotto che intende valorizzarle tutte quante, indicandole in maniera specifica e opportuna.<\/p>\n<p>Si presenta infatti adatto in quattro ambiti: come un\u00a0condimento alimentare a crudo, come un\u00a0cosmetico naturale al 100%, come protezione della salute e di prevenzione\u00a0e, infine, come conosciuto dai pi\u00f9,\u00a0ottimo in cucina. E\u2019 stato denominato <strong>Nect\u00e0rea<\/strong> e punta ad essere venduto in erboristeria, nei negozi di cosmetica e persino nelle farmacie, oltre che, naturalmente, nei negozi.<\/p>\n<p>E\u2019 stato ideato e, da pochi giorni, commercializzato dal gruppo di promozione della \u201cDieta Med-Italiana\u201d ed \u00e8 prodotto presso la Cooperativa Sant\u2019Anna di Vernole (Le).<\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2013\/01\/07\/olio-nettare-degli-dei-arriva-nectarea\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2013\/01\/07\/olio-nettare-degli-dei-arriva-nectarea\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>Piccolo spazio pubblicit\u00e0 (gratuito)\u2026 E\u2019 risaputo che le propriet\u00e0 e le qualit\u00e0 dell\u2019olio extravergine d\u2019oliva vanno ben oltre il semplice condimento in cucina. Nasce adesso un prodotto che intende valorizzarle tutte quante, indicandole in maniera specifica e opportuna. Si presenta infatti adatto in quattro ambiti: come un\u00a0condimento alimentare a crudo, come un\u00a0cosmetico naturale al 100%, [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[1],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/9736"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=9736"}],"version-history":[{"count":3,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/9736\/revisions"}],"predecessor-version":[{"id":9740,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/9736\/revisions\/9740"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=9736"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=9736"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=9736"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}