{"id":977,"date":"2012-05-17T16:42:44","date_gmt":"2012-05-17T16:42:44","guid":{"rendered":"http:\/\/www.leccecronaca.it\/wordpress\/?p=977"},"modified":"2012-05-17T16:44:14","modified_gmt":"2012-05-17T16:44:14","slug":"strage-di-piazza-della-loggia-a-brescia-dopo-38-anni-la-cassazione-assolve-tutti-gli-imputati","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2012\/05\/17\/strage-di-piazza-della-loggia-a-brescia-dopo-38-anni-la-cassazione-assolve-tutti-gli-imputati\/","title":{"rendered":"Strage di Piazza della Loggia a Brescia dopo 38 anni, la Cassazione assolve tutti gli imputati"},"content":{"rendered":"<p>Anonimo via e-mail.<\/p>\n<p>Lo si poteva immaginare che la verit\u00e0 non sarebbe venuta a galla.<\/p>\n<p>Perch\u00e9 la politica su quella strage ha imposto la sua verit\u00e0, la verit\u00e0 che gli faceva comodo, quella verit\u00e0 che serviva per criminalizzare l\u2019avversario.<\/p>\n<p>Ricordo ancora distintamente, nonostante siano passati trentotto \u00a0anni, il presentatore televisivo che, cupo in volto, durante il telegiornale della sera d\u00e0 la tremenda notizia:<\/p>\n<p>una bomba \u00e8 scoppiata in piazza a Brescia durante una manifestazione antifascista, non si sa chi \u00e8 stato non \u00e8 stato preso nessuno ma la bomba \u00e8 di chiara marca fascista.<\/p>\n<p>Avevo 17 anni iniziavo da poco ad interessarmi di politica, ma quella\u201dchiara marca fascista\u201d mi rest\u00f2 impressa. Una bomba non \u00e8 un detersivo non ha una marca, non ha un\u2019etichetta che ti riconduce a chi l\u2019ha confezionata, una bomba messa durante una manifestazione pu\u00f2 dare adito a mille interpretazioni.<\/p>\n<p>A chi serviva quella bomba? E a chi serv\u00ec?<\/p>\n<p>La bomba \u00e8 di chiara marca fascista disse il telegiornale, ed erano i tempi in cui quando la gente diceva lo ha detto il telegiornale era come dire che quella notizia era verit\u00e0 incontrovertibile.<\/p>\n<p>A chi serv\u00ec? Non lo sappiamo, ma quella come le altre, sappiamo a cosa serv\u00ec\u2026.ad eliminare definitivamente dal panorama politico e culturale la destra italiana.<\/p>\n<p>Ai comunisti non sembr\u00f2 vero, poter infangare l\u2019avversario storico definitivamente, alla Democrazia Cristiana ed ai suoi alleati, poter governare per altri trenta anni, spaventando i cittadini con la teoria degli opposti estremismi.<\/p>\n<p>Meglio i ladri che gli assassini, un assioma che tenne bloccato il paese per decenni, intanto i partiti rubavano, dilapidavano le ingenti risorse economiche e morali del paese, fecero crescere all\u2019infinito il debito pubblico, comprando il consenso\u2026Ed oggi purtroppo tutto ci\u00f2 appare evidente.<\/p>\n<p>Ma torniamo alla strage.<\/p>\n<p>Trentotto \u00a0anni di indagini, tre distinti filoni, processi in tre diverse citt\u00e0, decine e decine di Magistrati, centinaia di persone indagate, arrestate, prima condannate e poi assolte.<\/p>\n<p>Prima furono accusati i fascisti di Brescia, poi si disse che erano stati quelli di Roma\u2026..di Milano di Venezia, decine di nomi sconosciuti, infine per rendere pi\u00f9 credibile l\u2019impianto accusatorio ai danni della destra, si pens\u00f2 di incriminare lo stesso on. Pino Rauti, che per anni sar\u00e0 perseguitato da questo processo.<\/p>\n<p>Accuse infamanti che spesso hanno distrutto la serenit\u00e0 di tanti innocenti anche questi vittime che si aggiungono a quelle dilaniate dalla bomba.<\/p>\n<p>Questo avviene quando a tutti i costi si persegue una verit\u00e0 di parte, da utilizzare per fini politici.<\/p>\n<p>La Magistratura non \u00e8 riuscita a trovare i colpevoli, ma la politica s\u00ec, il colpevole \u00e8 il fascista, per forza. Non importa chi sia, dove abiti, da dove sia venuto, se sia giovane o vecchio e perch\u00e9 abbia messo quella bomba, ma sicuramente sar\u00e0 stato lui, il fascista brutto nero e cattivo.<\/p>\n<p>Eppure risultava evidente che di mezzo vi erano i cosiddetti \u201dservizi\u201d, ossia i Servizi segreti, e quindi lo Stato, e allora per non contraddire il teorema inquisitorio, si raccontava la favola dei servizi deviati. Deviati da chi? E per raggiungere quale obbiettivo? Qui ci si arrampicava sugli specchi, e ci hanno raccontato di tutto in questi trentotto anni.<\/p>\n<p>La Magistratura non ha scoperto la verit\u00e0 per il momento, ma, quale che questa sia, certo \u00e8, che \u201cla verit\u00e0 politica\u201d che \u00e8 passata alla storia in tanti \u00a0anni di menzogne \u00e8, che la strage \u00e8 stata compiuta dai fascisti, cos\u00ec come aveva detto la televisione quella sera.<\/p>\n<p>Oggi lo stesso Presidente dell\u2019Associazione Caduti di Piazza della Loggia, Manlio Milani dice: \u00abPurtroppo il vero danno a questo processo \u00e8 stato fatto all\u2019inizio in modo particolare con il lavaggio della piazza, che ha impedito di ricostruire l\u2019esplosivo usato e il detonatore utilizzato &#8211; osserva Milani -. Ancora una volta ci troviamo di fronte a un fatto che dopo trentotto anni non ha ancora giustizia: dimostra che questa democrazia \u00e8 in bal\u00eca degli eventi, la mancanza di trasparenza nelle istituzioni e la mancanza di volont\u00e0 di parlare al paese\u00bb.<\/p>\n<p>Il Tribunale ha condannato alle spese i parenti delle vittime; Walter Veltroni ha<\/p>\n<p>chiesto che se ne facciano carico i partiti: \u00e8 il minimo che possono fare dopo aver strumentalizzato per 40 anni il dolore\u00a0 e la buona fede di queste povere persone.<\/p>\n<p>&nbsp;<\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2012\/05\/17\/strage-di-piazza-della-loggia-a-brescia-dopo-38-anni-la-cassazione-assolve-tutti-gli-imputati\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2012\/05\/17\/strage-di-piazza-della-loggia-a-brescia-dopo-38-anni-la-cassazione-assolve-tutti-gli-imputati\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>Anonimo via e-mail. Lo si poteva immaginare che la verit\u00e0 non sarebbe venuta a galla. Perch\u00e9 la politica su quella strage ha imposto la sua verit\u00e0, la verit\u00e0 che gli faceva comodo, quella verit\u00e0 che serviva per criminalizzare l\u2019avversario. Ricordo ancora distintamente, nonostante siano passati trentotto \u00a0anni, il presentatore televisivo che, cupo in volto, durante [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":980,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[36],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/977"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=977"}],"version-history":[{"count":3,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/977\/revisions"}],"predecessor-version":[{"id":979,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/977\/revisions\/979"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/980"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=977"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=977"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=977"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}