{"id":9790,"date":"2013-01-08T12:28:01","date_gmt":"2013-01-08T12:28:01","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=9790"},"modified":"2013-01-08T12:28:01","modified_gmt":"2013-01-08T12:28:01","slug":"poesia-il-nostro-nicola-vacca-ci-prendeper-il-verso-giusto","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2013\/01\/08\/poesia-il-nostro-nicola-vacca-ci-prendeper-il-verso-giusto\/","title":{"rendered":"Poesia\/ Il nostro Nicola Vacca ci prende\u2026per il verso giusto"},"content":{"rendered":"<p><strong><a href=\"https:\/\/www.leccecronaca.it\/index.php\/2013\/01\/08\/poesia-il-nostro-nicola-vacca-ci-prendeper-il-verso-giusto\/cittdidio1\/\" rel=\"attachment wp-att-9791\"><img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2013\/01\/cittdidio1-150x150.jpg\" alt=\"\" width=\"150\" height=\"150\" class=\"alignleft size-thumbnail wp-image-9791\" \/><\/a>Due momenti di riflessione mistica, due nuove poesie del nostro poeta Nicola Vacca, due occasione di colloquio interiore ( nella foto, una scena del film \u201cLa citt\u00e0 di Dio\u201d di Fernando Meirelles).<\/strong><\/p>\n<p><strong>\u00a0***<\/strong><\/p>\n<p><strong>La parola di Dio<\/strong><\/p>\n<p><strong>\u00a0<\/strong>La parola di Dio<\/p>\n<p>\u00e8 grazia del resistere<\/p>\n<p>davanti alle troppe rese<\/p>\n<p>che la vita impone.<\/p>\n<p>La parola di Dio<\/p>\n<p>non \u00e8 solo il Verbo<\/p>\n<p>\u00e8 la possibilit\u00e0 che il cammino riprenda<\/p>\n<p>anche se la strada \u00e8 dissestata.<\/p>\n<p>***<\/p>\n<p><strong>La realt\u00e0 \u00e8 servita<\/strong><\/p>\n<p>Tuffi nel vuoto<\/p>\n<p>cadute nei precipizi.<\/p>\n<p>Eppure si cerca<\/p>\n<p>un barlume della citt\u00e0 di Dio<\/p>\n<p>in questa cecit\u00e0<\/p>\n<p>che annebbia i luoghi.<\/p>\n<p>Adesso si collezionano<\/p>\n<p>piccoli compendi\u00a0 di sconfitte<\/p>\n<p>la realt\u00e0 \u00e8 servita<\/p>\n<p>dal catalogo delle dissonanze.<\/p>\n<p>Il nostro tempo vive<\/p>\n<p>un trapasso di civilt\u00e0.<\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2013\/01\/08\/poesia-il-nostro-nicola-vacca-ci-prendeper-il-verso-giusto\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2013\/01\/08\/poesia-il-nostro-nicola-vacca-ci-prendeper-il-verso-giusto\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>Due momenti di riflessione mistica, due nuove poesie del nostro poeta Nicola Vacca, due occasione di colloquio interiore ( nella foto, una scena del film \u201cLa citt\u00e0 di Dio\u201d di Fernando Meirelles). \u00a0*** La parola di Dio \u00a0La parola di Dio \u00e8 grazia del resistere davanti alle troppe rese che la vita impone. La parola [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[1],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/9790"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=9790"}],"version-history":[{"count":3,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/9790\/revisions"}],"predecessor-version":[{"id":9794,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/9790\/revisions\/9794"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=9790"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=9790"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=9790"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}