{"id":9820,"date":"2013-01-08T18:46:11","date_gmt":"2013-01-08T18:46:11","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=9820"},"modified":"2013-01-08T18:46:11","modified_gmt":"2013-01-08T18:46:11","slug":"nascondeva-in-macchina-armi-e-munizionifermato-dai-carabinieri-giovane-brindisino","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2013\/01\/08\/nascondeva-in-macchina-armi-e-munizionifermato-dai-carabinieri-giovane-brindisino\/","title":{"rendered":"Nascondeva in macchina armi e munizioni\/FERMATO DAI CARABINIERI GIOVANE BRINDISINO"},"content":{"rendered":"<p><a href=\"https:\/\/www.leccecronaca.it\/index.php\/2013\/01\/08\/nascondeva-in-macchina-armi-e-munizionifermato-dai-carabinieri-giovane-brindisino\/dsc02027-600-x-399\/\" rel=\"attachment wp-att-9821\"><img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2013\/01\/DSC02027-600-x-399-300x199.jpg\" alt=\"\" width=\"300\" height=\"199\" class=\"alignleft size-medium wp-image-9821\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2013\/01\/DSC02027-600-x-399-300x199.jpg 300w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2013\/01\/DSC02027-600-x-399.jpg 600w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>E\u2019 stato fermato questo pomeriggio e si trova adesso al carcere di Borgo San Nicola, a disposizione del magistrato di turno, il sostituto procurato Antonio Negro, che decider\u00e0 sulla convalida dell\u2019arresto, Alessandro Pell\u00e9, 37 anni, brindisino, residente a San Cesario di Lecce. Era San Pietro in Lama. Nel corso di un consueto servizio di perlustrazione del territori, in quest\u2019ultimo periodo incrementati in relazione al compimento di rapine in abitazione, i carabinieri lo hanno notato in atteggiamento sospetto in via Sabaudia e lo hanno sottoposto a\u00a0 controllo.<\/p>\n<p>All\u2019interno della autovettura, occultati in un borsone riposto dietro al sedile passeggero, \u00e8 venuto fuori di tutto, di pi\u00f9 (nella foto): un coltello a serramanico, un fucile a pompa calibro 12, una pistola semiautomatica calibro 7,65, entrambi forniti di relativo munizionamento e con matricola abrasa, \u00a0munizioni, guanti in lattice, passamontagna, nastro adesivo e vernice spray.<\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2013\/01\/08\/nascondeva-in-macchina-armi-e-munizionifermato-dai-carabinieri-giovane-brindisino\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2013\/01\/08\/nascondeva-in-macchina-armi-e-munizionifermato-dai-carabinieri-giovane-brindisino\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>E\u2019 stato fermato questo pomeriggio e si trova adesso al carcere di Borgo San Nicola, a disposizione del magistrato di turno, il sostituto procurato Antonio Negro, che decider\u00e0 sulla convalida dell\u2019arresto, Alessandro Pell\u00e9, 37 anni, brindisino, residente a San Cesario di Lecce. Era San Pietro in Lama. Nel corso di un consueto servizio di perlustrazione [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[69],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/9820"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=9820"}],"version-history":[{"count":2,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/9820\/revisions"}],"predecessor-version":[{"id":9823,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/9820\/revisions\/9823"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=9820"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=9820"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=9820"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}