{"id":99834,"date":"2016-10-13T10:04:26","date_gmt":"2016-10-13T08:04:26","guid":{"rendered":"http:\/\/www.leccecronaca.it\/?p=99834"},"modified":"2016-10-13T15:40:54","modified_gmt":"2016-10-13T13:40:54","slug":"un-arresto-per-stalking-ad-aradeo","status":"publish","type":"post","link":"https:\/\/www.leccecronaca.it\/index.php\/2016\/10\/13\/un-arresto-per-stalking-ad-aradeo\/","title":{"rendered":"UN ARRESTO PER STALKING AD ARADEO"},"content":{"rendered":"<p><img decoding=\"async\" loading=\"lazy\" width=\"490\" height=\"325\" title=\"1-aradeo-metc3a0-secolo\" class=\"aligncenter size-full wp-image-99840\" alt=\"\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2016\/10\/1-aradeo-metc3a0-secolo.jpg\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2016\/10\/1-aradeo-metc3a0-secolo.jpg 490w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2016\/10\/1-aradeo-metc3a0-secolo-300x199.jpg 300w\" sizes=\"(max-width: 490px) 100vw, 490px\" \/>(f.p.)______(a tutela della vittima e dei minorenni, abbiamo omesso le generalit\u00e0 dell&#8217; arrestato e ogni altro elemento che possa permettere l&#8217; individuazione degli interessati)______Brutta storia di stalking, ancora un episodio nei nostri paesi. Un giovane di 34 anni di Aradeo (nella foto)\u00a0\u00e8 stato arrestato e portato in carcere a Lecce, su provvedimento emesso dal gip Stefano Sernia, dopo le indagini condotte dai militari dell&#8217; arma e coordinate dal sostituto procuratore Maria Rosaria Micucci, con l&#8217;accusa di estorsione, minacce, violenze fisiche e psichiche<\/p>\n<p>Secondo la ricostruzione del magistrato,\u00a0minacciava la convivente, anche con una pistola ad aria compressa (nella foto), o con\u00a0la lama di un taglierino, allo scopo di farsi consegnare da lei buona parte dello stipendio, oltre a perseguitarla, anche in presenza dei figli della donna,\u00a0con vessazioni e soprusi, e procurarle lesioni fisiche.<\/p>\n<p><img decoding=\"async\" loading=\"lazy\" width=\"225\" height=\"300\" title=\"A\" class=\"alignleft size-medium wp-image-99876\" alt=\"\" src=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2016\/10\/A1-225x300.jpg\" srcset=\"https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2016\/10\/A1-225x300.jpg 225w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2016\/10\/A1-768x1024.jpg 768w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2016\/10\/A1-1152x1536.jpg 1152w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2016\/10\/A1-1536x2048.jpg 1536w, https:\/\/www.leccecronaca.it\/wordpress\/wp-content\/uploads\/2016\/10\/A1-scaled.jpg 1920w\" sizes=\"(max-width: 225px) 100vw, 225px\" \/><\/p>\n<fb:like href='https:\/\/www.leccecronaca.it\/index.php\/2016\/10\/13\/un-arresto-per-stalking-ad-aradeo\/' send='true' layout='button_count' show_faces='true' width='450' height='65' action='recommend' colorscheme='light' font='lucida grande'><\/fb:like><span class=\"fb_share\"><fb:like href=\"https:\/\/www.leccecronaca.it\/index.php\/2016\/10\/13\/un-arresto-per-stalking-ad-aradeo\/\" layout=\"button_count\"><\/fb:like><\/span>","protected":false},"excerpt":{"rendered":"<p>(f.p.)______(a tutela della vittima e dei minorenni, abbiamo omesso le generalit\u00e0 dell&#8217; arrestato e ogni altro elemento che possa permettere l&#8217; individuazione degli interessati)______Brutta storia di stalking, ancora un episodio nei nostri paesi. Un giovane di 34 anni di Aradeo (nella foto)\u00a0\u00e8 stato arrestato e portato in carcere a Lecce, su provvedimento emesso dal gip [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":99840,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[69],"tags":[],"_links":{"self":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/99834"}],"collection":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/comments?post=99834"}],"version-history":[{"count":5,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/99834\/revisions"}],"predecessor-version":[{"id":99877,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/posts\/99834\/revisions\/99877"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media\/99840"}],"wp:attachment":[{"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/media?parent=99834"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/categories?post=99834"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leccecronaca.it\/index.php\/wp-json\/wp\/v2\/tags?post=99834"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}